{"id":44702,"date":"1997-01-01T00:00:00","date_gmt":"1997-01-01T05:00:00","guid":{"rendered":"http:\/\/www.cec.org\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/"},"modified":"2023-04-15T19:32:31","modified_gmt":"2023-04-15T23:32:31","slug":"les-mouvements-de-polluants-a-lechelle-du-continent","status":"publish","type":"publications","link":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/","title":{"rendered":"Les mouvements de polluants \u00e0 l&rsquo;\u00e9chelle du continent"},"content":{"rendered":"<p>L'Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l'environnement (ANACDE) est entr\u00e9 en vigueur en m\u00eame temps que l'Accord de libre-\u00e9change nord-am\u00e9ricain (AL\u00c9NA), le 1 er janvier 1994. L'ANACDE a \u00e9t\u00e9 conclu pour \u00e9tablir un cadre de coop\u00e9ration environnementale \u00e0 l'\u00e9chelle du continent, pour r\u00e9agir aux pr\u00e9occupations relatives aux effets possibles de la lib\u00e9ralisation des \u00e9changes et du ren-forcement de l'int\u00e9gration \u00e9conomique sur l'environnement nord-am\u00e9ricain et pour promouvoir la mise sur pied d'un programme environnemental regroupant les trois pays et portant sur des enjeux d'envergure r\u00e9gio-nale et d'int\u00e9r\u00eat commun.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l&rsquo;environnement (ANACDE) est entr\u00e9 en vigueur en m\u00eame temps que l&rsquo;Accord de libre-\u00e9change nord-am\u00e9ricain (AL\u00c9NA), le 1 er janvier 1994. L&rsquo;ANACDE a \u00e9t\u00e9 conclu pour \u00e9tablir un cadre de coop\u00e9ration environnementale \u00e0 l&rsquo;\u00e9chelle du continent, pour r\u00e9agir aux pr\u00e9occupations relatives aux effets possibles de la lib\u00e9ralisation des [&hellip;]<\/p>\n","protected":false},"featured_media":42728,"template":"","class_list":["post-44702","publications","type-publications","status-publish","has-post-thumbnail","hentry","document_type-rapport-independant-du-secretariat","document_theme-polluants"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les mouvements de polluants \u00e0 l&#039;\u00e9chelle du continent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les mouvements de polluants \u00e0 l&#039;\u00e9chelle du continent\" \/>\n<meta property=\"og:description\" content=\"L&#039;Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l&#039;environnement (ANACDE) est entr\u00e9 en vigueur en m\u00eame temps que l&#039;Accord de libre-\u00e9change nord-am\u00e9ricain (AL\u00c9NA), le 1 er janvier 1994. L&#039;ANACDE a \u00e9t\u00e9 conclu pour \u00e9tablir un cadre de coop\u00e9ration environnementale \u00e0 l&#039;\u00e9chelle du continent, pour r\u00e9agir aux pr\u00e9occupations relatives aux effets possibles de la lib\u00e9ralisation des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-15T23:32:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"465\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/\",\"name\":\"Les mouvements de polluants \u00e0 l'\u00e9chelle du continent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png\",\"datePublished\":\"1997-01-01T05:00:00+00:00\",\"dateModified\":\"2023-04-15T23:32:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png\",\"width\":465,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/les-mouvements-de-polluants-a-lechelle-du-continent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publications\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/publications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les mouvements de polluants \u00e0 l&rsquo;\u00e9chelle du continent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les mouvements de polluants \u00e0 l'\u00e9chelle du continent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/","og_locale":"fr_FR","og_type":"article","og_title":"Les mouvements de polluants \u00e0 l'\u00e9chelle du continent","og_description":"L'Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l'environnement (ANACDE) est entr\u00e9 en vigueur en m\u00eame temps que l'Accord de libre-\u00e9change nord-am\u00e9ricain (AL\u00c9NA), le 1 er janvier 1994. L'ANACDE a \u00e9t\u00e9 conclu pour \u00e9tablir un cadre de coop\u00e9ration environnementale \u00e0 l'\u00e9chelle du continent, pour r\u00e9agir aux pr\u00e9occupations relatives aux effets possibles de la lib\u00e9ralisation des [&hellip;]","og_url":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2023-04-15T23:32:31+00:00","og_image":[{"width":465,"height":600,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/","url":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/","name":"Les mouvements de polluants \u00e0 l'\u00e9chelle du continent","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png","datePublished":"1997-01-01T05:00:00+00:00","dateModified":"2023-04-15T23:32:31+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-fr.png","width":465,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/publications\/les-mouvements-de-polluants-a-lechelle-du-continent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Publications","item":"https:\/\/www.cec.org\/fr\/publications\/"},{"@type":"ListItem","position":3,"name":"Les mouvements de polluants \u00e0 l&rsquo;\u00e9chelle du continent"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/fr\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/fr\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/publications\/44702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/publications"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media\/42728"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=44702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}