{"id":48964,"date":"2022-06-03T12:17:08","date_gmt":"2022-06-03T16:17:08","guid":{"rendered":"http:\/\/www.cec.org\/media\/media-releases\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/"},"modified":"2022-06-03T12:17:08","modified_gmt":"2022-06-03T16:17:08","slug":"la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique","status":"publish","type":"news","link":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/","title":{"rendered":"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d&rsquo;un projet et de la pollution \u00e0 Playa Hermosa, au Mexique"},"content":{"rendered":"<p><strong>Montreal, le 3 juin\u00a02022 \u2014\u00a0<\/strong>Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0 la\u00a0<a href=\"https:\/\/www.cec.org\/fr\/\">Commission de coop\u00e9ration environnementale<\/a>\u00a0(CCE) une\u00a0<a href=\"http:\/\/www.cec.org\/wp-content\/uploads\/wpallimport\/files\/22-1-sub_es.pdf\" target=\"_blank\" rel=\"noopener\">communication<\/a>, en vertu du\u00a0<a href=\"http:\/\/www.cec.org\/wp-content\/uploads\/cce-aceum-et-eca.pdf\">chapitre 24<\/a>\u00a0de l\u2019<em>Accord Canada-\u00c9tats-Unis-Mexique<\/em>\u00a0(ACEUM), dans laquelle les auteurs all\u00e8guent que le Mexique omet d\u2019assurer l\u2019application efficace de ses lois de l\u2019environnement en ne prot\u00e9geant pas l\u2019\u00e9cosyst\u00e8me c\u00f4tier de Playa Hermosa, une plage locale situ\u00e9e \u00e0 Ensenada, en Basse-Californie.<\/p>\n<p>Les auteurs soutiennent que les autorit\u00e9s \u00e9tatiques et municipales m\u00e8nent un projet d\u2019am\u00e9nagement d\u2019une promenade et du front de mer \u00e0 Playa Hermosa, et ce, sans d\u00e9tenir les permis f\u00e9d\u00e9raux n\u00e9cessaires relativement aux r\u00e9percussions environnementales de ce projet. Ils affirment \u00e9galement que la qualit\u00e9 de l\u2019eau dans le secteur est compromise par les rejets d\u2019eaux us\u00e9es qui ne sont pas trait\u00e9s ad\u00e9quatement, mais aussi que les travaux de construction ont entra\u00een\u00e9 la destruction des dunes de Playa Hermosa l\u2019an dernier et qu\u2019aucune mesure n\u2019a \u00e9t\u00e9 prise en vue de les restaurer.<\/p>\n<p>Selon les auteurs, la Playa Hermosa est une plage que fr\u00e9quentent les r\u00e9sidants d\u2019Ensenada, car il s\u2019agit de la seule plage accessible \u00e0 partir de cette ville, et qu\u2019elle est importante pour l\u2019\u00e9conomie locale. Ils ajoutent que cet endroit est l\u2019un des rares o\u00f9 il est possible de pratiquer des activit\u00e9s ext\u00e9rieures en toute s\u00e9curit\u00e9 dans le contexte de la pand\u00e9mie de COVID-19.<\/p>\n<p>Ils soutiennent que le Mexique n\u2019applique pas efficacement la\u00a0<em>Ley General del Equilibrio Ecol\u00f3gico y la Protecci\u00f3n al Ambiente<\/em>\u00a0(LGEEPA, Loi g\u00e9n\u00e9rale sur l\u2019\u00e9quilibre \u00e9cologique et la protection de l\u2019environnement), son r\u00e8glement sur les r\u00e9percussions environnementales, la\u00a0<em>Ley de Aguas Nacionales<\/em>\u00a0(LAN, Loi sur les eaux nationales) et les r\u00e8glements connexes, la\u00a0<em>Ley General de Cambio Clim\u00e1tico<\/em>\u00a0(LGCC, Loi g\u00e9n\u00e9rale sur les changements climatiques), ainsi que d\u2019autres dispositions de lois et r\u00e8glements f\u00e9d\u00e9raux.<\/p>\n<p>Le Secr\u00e9tariat examinera la communication et d\u00e9terminera si elle satisfait aux exigences des paragraphes 24.27(2) et (3) de l\u2019ACEUM. Pour en savoir davantage \u00e0 son sujet, il est possible de la consulter en cliquant sur le lien\u00a0<a href=\"https:\/\/www.cec.org\/fr\/communications-sur-les-questions-dapplication\/registre-des-communications\/pollution-a-playa-hermosa\/\" target=\"_blank\" rel=\"noopener\">SEM-22-001 (<em>Pollution \u00e0 Playa Hermosa<\/em>)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0 la\u00a0Commission de coop\u00e9ration environnementale\u00a0(CCE) une\u00a0communication, en vertu du\u00a0chapitre 24\u00a0de l\u2019Accord Canada-\u00c9tats-Unis-Mexique\u00a0(ACEUM), dans laquelle les auteurs all\u00e8guent que le Mexique omet d\u2019assurer l\u2019application efficace de ses lois de l\u2019environnement en ne prot\u00e9geant pas [&hellip;]<\/p>\n","protected":false},"featured_media":48961,"template":"","class_list":["post-48964","news","type-news","status-publish","has-post-thumbnail","hentry","feed-sem-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d&#039;un projet et de la pollution \u00e0 Playa Hermosa, au Mexique<\/title>\n<meta name=\"description\" content=\"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d&#039;un projet et de la pollution \u00e0 Playa Hermosa, au Mexique\" \/>\n<meta property=\"og:description\" content=\"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/sem-playa-hermosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/\",\"name\":\"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d'un projet et de la pollution \u00e0 Playa Hermosa, au Mexique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/sem-playa-hermosa.jpg\",\"datePublished\":\"2022-06-03T16:17:08+00:00\",\"description\":\"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/sem-playa-hermosa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/sem-playa-hermosa.jpg\",\"width\":600,\"height\":342,\"caption\":\"Submission asserts failure to enforce environmental law in Mexico to protect a coastal ecosystem in Ensenada, Baja California.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/nouvelles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d&rsquo;un projet et de la pollution \u00e0 Playa Hermosa, au Mexique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"alternateName\":\"CEC - CCA -CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d'un projet et de la pollution \u00e0 Playa Hermosa, au Mexique","description":"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/","og_locale":"fr_FR","og_type":"article","og_title":"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d'un projet et de la pollution \u00e0 Playa Hermosa, au Mexique","og_description":"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0","og_url":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","og_image":[{"width":600,"height":342,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/sem-playa-hermosa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/","url":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/","name":"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d'un projet et de la pollution \u00e0 Playa Hermosa, au Mexique","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/sem-playa-hermosa.jpg","datePublished":"2022-06-03T16:17:08+00:00","description":"Montreal, le 3 juin\u00a02022 \u2014\u00a0Un groupe de six organisations d\u2019\u00e9cologistes, de patineurs, de surfeurs et de jeunes (ci-apr\u00e8s les \u00ab\u00a0auteurs\u00a0\u00bb) a pr\u00e9sent\u00e9 \u00e0","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/sem-playa-hermosa.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/sem-playa-hermosa.jpg","width":600,"height":342,"caption":"Submission asserts failure to enforce environmental law in Mexico to protect a coastal ecosystem in Ensenada, Baja California."},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/nouvelles\/la-cce-recoit-une-communication-en-vertu-du-chapitre-24-de-laceum-qui-fait-etat-des-repercussions-environnementales-dun-projet-et-de-la-pollution-a-playa-hermosa-au-mexique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/www.cec.org\/fr\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"La CCE re\u00e7oit une communication en vertu du chapitre 24 de l\u2019ACEUM qui fait \u00e9tat des r\u00e9percussions environnementales d&rsquo;un projet et de la pollution \u00e0 Playa Hermosa, au Mexique"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","alternateName":"CEC - CCA -CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/news\/48964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media\/48961"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=48964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}