{"id":11320,"date":"2015-12-02T18:24:59","date_gmt":"2015-12-02T23:24:59","guid":{"rendered":"http:\/\/www.cec.org\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/"},"modified":"2024-06-22T12:29:26","modified_gmt":"2024-06-22T16:29:26","slug":"communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel","status":"publish","type":"grants","link":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/","title":{"rendered":"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel"},"content":{"rendered":"<h4>Description du probl\u00e8me<\/h4>\n<p>Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur territoire. Or la pr\u00e9servation des \u00e9cosyst\u00e8mes est essentielle au d\u00e9veloppement durable de ces communaut\u00e9s. En outre, l\u2019av\u00e8nement de projets de d\u00e9veloppement industriel accentue l'urgence de proc\u00e9der \u00e0 des exercices de planification et de veiller \u00e0 bien prendre en compte les pr\u00e9occupations de ces collectivit\u00e9s pour garantir un avenir viable \u00e0 leurs membres.<\/p>\n<h4>Objectifs<\/h4>\n<p>Le projet vise \u00e0 fournir un soutien technique et strat\u00e9gique aux communaut\u00e9s nordiques en mati\u00e8re d\u2019acquisition de connaissances \u00e9cologiques et culturelles, de planification territoriale et de protection des \u00e9cosyst\u00e8mes.<\/p>\n<h4>Principales activit\u00e9s<\/h4>\n<p>\u00c9laboration de modules de formation sur les aires prot\u00e9g\u00e9es et d\u2019autres outils de conservation ; identification des sites de conservation prioritaires; organisation d\u2019ateliers pour favoriser l'\u00e9change de comp\u00e9tences et de connaissances; organisation d\u2019activit\u00e9s de plein air sur le territoire et formation de leaders en conservation.<\/p>\n<h4>R\u00e9sultats<\/h4>\n<p>Le projet permettra de renforcer les capacit\u00e9s des collectivit\u00e9s nordiques afin qu\u2019elles pratiquent une gestion responsable de l'environnement et priorisent l\u2019int\u00e9gration de leurs pr\u00e9occupations dans les projets de d\u00e9veloppement \u00e0 venir, et ce, gr\u00e2ce \u00e0 l'acquisition de connaissances, \u00e0 la production d'outils de conservation et de communication pour prot\u00e9ger leur territoire et \u00e0 la formation de leaders et d'experts en conservation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur territoire. Or la pr\u00e9servation des \u00e9cosyst\u00e8mes est essentielle au d\u00e9veloppement durable de ces communaut\u00e9s. En outre, l\u2019av\u00e8nement de projets de d\u00e9veloppement industriel accentue l&rsquo;urgence de proc\u00e9der \u00e0 des exercices de planification et [&hellip;]<\/p>\n","protected":false},"featured_media":3037,"template":"","class_list":["post-11320","grants","type-grants","status-publish","has-post-thumbnail","hentry","country-canada-fr","status-conclu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel<\/title>\n<meta name=\"description\" content=\"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel\" \/>\n<meta property=\"og:description\" content=\"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T16:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/napeca2015_project5_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/\",\"name\":\"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/napeca2015_project5_0.jpg\",\"datePublished\":\"2015-12-02T23:24:59+00:00\",\"dateModified\":\"2024-06-22T16:29:26+00:00\",\"description\":\"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/napeca2015_project5_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/napeca2015_project5_0.jpg\",\"width\":600,\"height\":513,\"caption\":\"Northern Communities\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel","description":"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/","og_locale":"fr_FR","og_type":"article","og_title":"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel","og_description":"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur","og_url":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-06-22T16:29:26+00:00","og_image":[{"width":600,"height":513,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/napeca2015_project5_0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/","url":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/","name":"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/napeca2015_project5_0.jpg","datePublished":"2015-12-02T23:24:59+00:00","dateModified":"2024-06-22T16:29:26+00:00","description":"Description du probl\u00e8me Les communaut\u00e9s nordiques sont souvent confront\u00e9es \u00e0 un manque de ressources et de moyens pour planifier la protection de leur","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/napeca2015_project5_0.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/napeca2015_project5_0.jpg","width":600,"height":513,"caption":"Northern Communities"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/north-american-partnership-for-environmental-community-action\/napeca-grants\/communautes-nordiques-durables-protection-du-territoire-et-maintien-du-mode-de-vie-traditionnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Communaut\u00e9s nordiques durables : protection du territoire et maintien du mode de vie traditionnel"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/fr\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/fr\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/grants\/11320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/grants"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/grants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media\/3037"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=11320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}