{"id":47762,"date":"2022-03-18T10:02:04","date_gmt":"2022-03-18T14:02:04","guid":{"rendered":"http:\/\/www.cec.org\/ej4climate\/ej4climate-grants\/arbres-temoins-de-turner-station\/"},"modified":"2025-04-28T13:03:33","modified_gmt":"2025-04-28T17:03:33","slug":"arbres-temoins-de-turner-station","status":"publish","type":"ej4climate","link":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/","title":{"rendered":"Arbres t\u00e9moins de Turner Station"},"content":{"rendered":"<h4>Contexte<\/h4>\n<p>Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques pr\u00e9voient que les collectivit\u00e9s c\u00f4ti\u00e8res du centre de la c\u00f4te de l\u2019Atlantique et de la baie de Chesapeake conna\u00eetront un nombre d\u2019inondations sup\u00e9rieur \u00e0 la moyenne en raison des effets combin\u00e9s de l\u2019affaissement du sol, de l\u2019\u00e9l\u00e9vation g\u00e9n\u00e9rale du niveau de la mer et du \u00ab gonflement \u00bb de l\u2019oc\u00e9an dans cette partie de l\u2019Atlantique. Baltimore subit \u00e9galement les cons\u00e9quences de la discrimination sous de multiples formes, dont l\u2019une est le nombre d\u2019arbres et d\u2019espaces verts consid\u00e9rablement inf\u00e9rieur dans les collectivit\u00e9s de personnes noires, autochtones et de couleur. Ce manque d\u2019investissement dans les infrastructures vertes de ces collectivit\u00e9s est notamment associ\u00e9 \u00e0 une moins bonne qualit\u00e9 de l\u2019air et de l\u2019eau, ainsi qu\u2019\u00e0 des taux plus \u00e9lev\u00e9s d\u2019asthme, de maladies cardiovasculaires, de probl\u00e8mes de sant\u00e9 mentale et de criminalit\u00e9.<\/p>\n<h4>Objectifs<\/h4>\n<p>L\u2019objectif du projet d\u2019\u00ab arbres t\u00e9moins \u00bb consiste \u00e0 se concentrer sur l\u2019action climatique directe, le renforcement des capacit\u00e9s en mati\u00e8re de justice environnementale et la documentation de l\u2019histoire orale, et ce, afin de faire progresser l\u2019adaptation aux changements climatiques, l\u2019\u00e9quit\u00e9 raciale et la r\u00e9silience communautaire dans deux collectivit\u00e9s de Baltimore peupl\u00e9es de personnes noires, autochtones et de couleur traditionnellement mal desservies. La majeure partie des travaux sera confi\u00e9e \u00e0 des jeunes de ces collectivit\u00e9s qui seront embauch\u00e9s et form\u00e9s pour devenir surveillants des arbres urbains. Les membres du groupe suivront \u00e9galement des cours sur les changements climatiques, l\u2019\u00e9cologie urbaine, la justice environnementale, le leadership communautaire, la communication et le travail d\u2019\u00e9quipe, des sujets qui sont tous en rapport avec les difficult\u00e9s qui persistent et les possibilit\u00e9s qui s\u2019offrent sur place. Le projet a pour but de valider le concept d\u2019une brigade pour le climat \u00e0 Baltimore, et \u00e0 le faire progresser dans tout le grand Baltimore.<\/p>\n<h4>Principales activit\u00e9s<\/h4>\n<ul>\n<li>Organiser une s\u00e9rie d\u2019ateliers pour former des jeunes de la r\u00e9gion comme surveillants des arbres urbains.<\/li>\n<li>Sensibiliser 50 r\u00e9sidents \u00e0 l\u2019\u00e9tat de l\u2019environnement, aux effets de la salubrit\u00e9 de l\u2019environnement sur la sant\u00e9 et la prosp\u00e9rit\u00e9 de la population, et aux possibilit\u00e9s de changer les choses.<\/li>\n<li>Organiser une s\u00e9rie d\u2019activit\u00e9s communautaires pour planter des arbres.<\/li>\n<\/ul>\n<h4>R\u00e9sultats<\/h4>\n<ul>\n<li>La plantation de 400 nouveaux arbres dans deux collectivit\u00e9s urbaines mal desservies par le pass\u00e9.<\/li>\n<li>La formation de 25 jeunes comme surveillants des arbres urbains.<\/li>\n<li>La sensibilisation de 50 r\u00e9sidants pour accro\u00eetre leurs connaissances et leur efficacit\u00e9 \u00e0 l\u2019\u00e9gard des probl\u00e8mes environnementaux qui s\u00e9vissent sur les plans local et mondial, et sur ce qu'il est possible de faire pour changer les choses.<\/li>\n<li>L\u2019\u00e9tablissement de deux plans d\u2019\u00e9cologisation pour guider les travaux de restauration des lieux et de renforcement de la r\u00e9silience qu'entreprendront les collectivit\u00e9s.<\/li>\n<li>L\u2019enregistrement audio de 20 histoires cont\u00e9es par des a\u00een\u00e9s locaux racontant ce qui s'est pass\u00e9 dans leur collectivit\u00e9, et dont les conclusions s\u2019entrem\u00ealeront avec la plantation des nouveaux arbres.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Contexte Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques pr\u00e9voient que les collectivit\u00e9s c\u00f4ti\u00e8res du centre de la c\u00f4te de l\u2019Atlantique et de la baie de Chesapeake conna\u00eetront un nombre d\u2019inondations sup\u00e9rieur \u00e0 la moyenne en raison des effets combin\u00e9s de l\u2019affaissement du sol, de [&hellip;]<\/p>\n","protected":false},"featured_media":47791,"template":"","class_list":["post-47762","ej4climate","type-ej4climate","status-publish","has-post-thumbnail","hentry","country-etats-unis","status-conclu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arbres t\u00e9moins de Turner Station<\/title>\n<meta name=\"description\" content=\"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbres t\u00e9moins de Turner Station\" \/>\n<meta property=\"og:description\" content=\"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T17:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/ej4climate-placeholder-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/\",\"name\":\"Arbres t\u00e9moins de Turner Station\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/ej4climate-placeholder-thumbnail.jpg\",\"datePublished\":\"2022-03-18T14:02:04+00:00\",\"dateModified\":\"2025-04-28T17:03:33+00:00\",\"description\":\"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/ej4climate-placeholder-thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/ej4climate-placeholder-thumbnail.jpg\",\"width\":1200,\"height\":684,\"caption\":\"\u00a9Photo by \u041c\u0438\u0445\u0430\u0438\u043b \u041f\u0430\u0432\u043b\u0435\u043d\u043a\u043e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/ej4climate\\\/subventions-ej4climate\\\/arbres-temoins-de-turner-station\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbres t\u00e9moins de Turner Station\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"alternateName\":\"CEC - CCA -CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arbres t\u00e9moins de Turner Station","description":"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/","og_locale":"fr_FR","og_type":"article","og_title":"Arbres t\u00e9moins de Turner Station","og_description":"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...","og_url":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2025-04-28T17:03:33+00:00","og_image":[{"width":1200,"height":684,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/ej4climate-placeholder-thumbnail.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/","url":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/","name":"Arbres t\u00e9moins de Turner Station","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/ej4climate-placeholder-thumbnail.jpg","datePublished":"2022-03-18T14:02:04+00:00","dateModified":"2025-04-28T17:03:33+00:00","description":"Baltimore est une ville portuaire postindustrielle situ\u00e9e dans le haut de la baie de Chesapeake. Les mod\u00e8les climatiques...","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/ej4climate-placeholder-thumbnail.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/ej4climate-placeholder-thumbnail.jpg","width":1200,"height":684,"caption":"\u00a9Photo by \u041c\u0438\u0445\u0430\u0438\u043b \u041f\u0430\u0432\u043b\u0435\u043d\u043a\u043e"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/ej4climate\/subventions-ej4climate\/arbres-temoins-de-turner-station\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Arbres t\u00e9moins de Turner Station"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","alternateName":"CEC - CCA -CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/ej4climate\/47762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/ej4climate"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/ej4climate"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media\/47791"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=47762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}