{"id":22858,"date":"2010-11-30T00:00:00","date_gmt":"2010-11-30T05:00:00","guid":{"rendered":"http:\/\/www.cec.org\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/"},"modified":"2024-07-11T16:20:48","modified_gmt":"2024-07-11T20:20:48","slug":"avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde","status":"publish","type":"documents","link":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/","title":{"rendered":"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE"},"content":{"rendered":"<p class=\"rteright\">DISTRIBUTION : G\u00e9n\u00e9rale<br \/>\nJ\/10-04\/ADV\/Final<br \/>\nORIGINAL : Anglais<\/p>\n<p><strong>Objet : \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Le Comit\u00e9 consultatif public mixte (CCPM) de la Commission de coop\u00e9ration environnementale (CCE) de l\u2019Am\u00e9rique du Nord;<\/p>\n<p><strong>EN CONFORMIT\u00c9<\/strong>\u00a0avec le paragraphe 16(4) de l\u2019Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l\u2019environnement (ANACDE), lequel stipule que le CCPM \u00ab pourra fournir des avis au Conseil sur toute question relevant du pr\u00e9sent accord [\u2026] ainsi que sur la mise en \u0153uvre et le d\u00e9veloppement du pr\u00e9sent accord[, et qu\u2019il] pourra exercer telles autres fonctions que lui confiera le Conseil \u00bb;<\/p>\n<p><strong>AYANT \u00c9TUDI\u00c9<\/strong>\u00a0l\u2019\u00e9bauche de la Proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE (ci-apr\u00e8s d\u00e9sign\u00e9e \u00ab la proposition \u00bb), en date du 29 juillet 2010;<\/p>\n<p><strong>RAPPELANT<\/strong>\u00a0au Conseil qu\u2019il a \u00e9tabli, \u00e0 son intention, le Rapport sur l\u2019examen de l\u2019efficacit\u00e9 du CCPM, en date du 18 f\u00e9vrier 2010, et qu\u2019il faudrait prendre ce rapport conjointement en consid\u00e9ration avec le pr\u00e9sent avis;<\/p>\n<p><strong>DONNANT SUITE<\/strong>\u00a0\u00e0 l\u2019invitation que lui a formul\u00e9e le Conseil lors de la session ordinaire que celui-ci a tenue \u00e0 Guanajuato, au Mexique, en ao\u00fbt dernier, \u00e0 savoir de lui adresser des suggestions pr\u00e9cises en vue de remanier la proposition;<\/p>\n<p><strong>SOUMET<\/strong>\u00a0\u00e0 l\u2019attention du Conseil les observations et recommandations qui suivent, en m\u00eame temps qu\u2019une copie annot\u00e9e de ladite proposition jointe en annexe :<\/p>\n<p><strong>1.\u00a0Port\u00e9e de la proposition<\/strong><\/p>\n<p>Le CCPM recommande que la proposition porte sur davantage de questions dans ce domaine, y compris la gouvernance relative au Conseil et au CCPM en plus de celle concernant le Secr\u00e9tariat, qui constitue le th\u00e8me central de cette proposition. Cons\u00e9quemment, l\u2019avis ci dessous expose les questions dont il faudrait traiter relativement \u00e0 chacun des trois \u00e9l\u00e9ments constitutifs de la CCE.<\/p>\n<p><strong>2.\u00a0Le Conseil<\/strong><\/p>\n<p>Le CCPM recommande que la proposition comprenne une nouvelle section portant sur les questions de gouvernance concernant le Conseil. Les recommandations qui suivent ont particuli\u00e8rement trait \u00e0 cette section :<\/p>\n<p><strong>2.1<\/strong>\u00a0\u00a0Le CCPM recommande que la proposition \u00e9nonce des normes d\u00e9taill\u00e9es de rendement comportant des \u00e9ch\u00e9ances \u00e0 l\u2019intention du Conseil (qu\u2019il s\u2019agisse des membres du Conseil, des repr\u00e9sentants suppl\u00e9ants ou des membres du Comit\u00e9 permanent g\u00e9n\u00e9ral), et ce, aux fins de l\u2019efficacit\u00e9 et du rendement, de la gouvernance en g\u00e9n\u00e9ral, de l\u2019orientation strat\u00e9gique, de l\u2019efficacit\u00e9 organisationnelle et de la diligence raisonnable requise par les processus et structures instaur\u00e9s par l\u2019ANACDE. Le CCPM se r\u00e9jouit de l\u2019inclusion d\u2019efforts afin de relancer les n\u00e9gociations visant la conclusion d\u2019un accord sur l\u2019\u00e9valuation des impacts environnementaux transfrontaliers, tel que le prescrit le paragraphe 10(7) de l\u2019ANACDE, \u00e9tant donn\u00e9 qu\u2019il s\u2019agit de l\u2019un des nombreux mandats \u00e0 inclure dans ces normes de rendement.<\/p>\n<p><strong>2.2<\/strong>\u00a0\u00a0Le CCPM est pr\u00e9occup\u00e9 par l\u2019accumulation de surplus budg\u00e9taires au cours des derni\u00e8res ann\u00e9es, surplus qui semblent d\u00e9couler en grande partie du retard \u00e0 \u00e9laborer et \u00e0 approuver les documents de planification. Notant que la proposition traite de cette question, le CCPM appuie l\u2019\u00e9laboration d\u2019une d\u00e9marche visant \u00e0 am\u00e9liorer le processus de soumission, par le Secr\u00e9tariat, des programme et budget annuels \u00e0 l\u2019approbation du Conseil (en vertu du paragraphe 11[6] de l\u2019ANACDE, tel que cela est \u00e9galement mentionn\u00e9 ci apr\u00e8s), ainsi que la formulation des observations par le public dont le CCPM tient compte en effectuant son propre examen de ces programme et budget.<\/p>\n<p><strong>2.3<\/strong>\u00a0\u00a0Notant que le CCPM et d\u2019autres entit\u00e9s, telles que le Comit\u00e9 consultatif national et le Comit\u00e9 consultatif gouvernemental am\u00e9ricains, sont tous d\u2019avis que le mandat de trois ans du directeur ex\u00e9cutif de la CCE est trop court pour \u00eatre efficace, et que le paragraphe 11(1) de l\u2019ANACDE prescrit que le directeur ex\u00e9cutif soit \u00ab nomm\u00e9 par le Conseil pour un mandat de trois ans, que le Conseil pourra renouveler une seule fois pour la m\u00eame dur\u00e9e \u00bb, le CCPM recommande au Conseil de faire preuve d\u2019une plus grande ouverture d\u2019esprit en renouvelant le mandat du directeur ex\u00e9cutif, \u00e0 condition que son rendement soit satisfaisant.<\/p>\n<p><strong>2.4<\/strong>\u00a0\u00a0Le CCPM recommande au Conseil que la proposition vise \u00e0 ce que tous les organes de la CCE soient ad\u00e9quatement repr\u00e9sent\u00e9s aux r\u00e9unions du Conseil (p. ex., les r\u00e9unions au cours desquelles les Parties \u00e0 l\u2019ANACDE examinent les affaires de la CCE), et d\u2019am\u00e9liorer la transparence des discussions en confiant au Secr\u00e9tariat le soin d\u2019\u00e9tablir des comptes rendus officiels de ces discussions et de les afficher dans le site Web de la CCE.<\/p>\n<p><strong>2.5<\/strong>\u00a0\u00a0Le CCPM r\u00e9it\u00e8re ses pr\u00e9occupations concernant les retards des votes du Conseil au sujet des recommandations de constitution de dossiers factuels en vertu du paragraphe 15(2) de l\u2019ANACDE. Ces retards constituent un inconvenant manque de d\u00e9f\u00e9rence envers l\u2019ind\u00e9pendance des \u00e9valuations du Secr\u00e9tariat lorsqu\u2019il recommande la constitution de dossiers factuels. Le CCPM sugg\u00e8re au Conseil de s\u2019engager, dans le cadre de la proposition, \u00e0 voter sur ces recommandations dans un d\u00e9lai de 120 jours.<\/p>\n<p><strong>2.6<\/strong>\u00a0\u00a0Le CCPM recommande que la proposition engage aussi le Conseil \u00e0 r\u00e9pondre aux avis et aux documents analogues du CCPM et d\u2019autres organes dans un d\u00e9lai de 90 jours.<\/p>\n<p><strong>3. \u00a0Le CCPM<\/strong><\/p>\n<p>Afin que les organes de la CCE s\u2019acquittent plus ad\u00e9quatement de leur mandat collectif consistant \u00e0 favoriser la transparence et la participation du public, le CCPM recommande que la proposition dresse un plan visant \u00e0 ce que ces organes puissent rejoindre une bien plus grande partie de la collectivit\u00e9.<\/p>\n<p><strong>4.\u00a0Le Secr\u00e9tariat<\/strong><\/p>\n<p><strong>4.1<\/strong>\u00a0Le CCPM note en outre que le paragraphe 11(6) de l\u2019ANACDE prescrit au Secr\u00e9tariat de \u00ab [soumettre] \u00e0 l\u2019approbation du Conseil le budget-programme annuel de la Commission \u00bb, et qu\u2019il confie clairement au Secr\u00e9tariat un r\u00f4le aussi important qu\u2019actif dans l\u2019\u00e9tablissement et la mise en \u0153uvre des plans op\u00e9rationnels et programmes de la CCE. Celle-ci faisait preuve de plus d\u2019efficacit\u00e9 et de rendement \u00e0 ses d\u00e9buts, lorsque le Secr\u00e9tariat se chargeait de pr\u00e9senter un programme. Mais, bien entendu, celui-ci doit \u00e9tablir un plan op\u00e9rationnel en tenant compte des directives du Conseil qu\u2019\u00e9nonce le plan strat\u00e9gique, et consulter les Parties, les groupes de travail et d\u2019autres entit\u00e9s en vue d\u2019\u00e9laborer le programme et le budget. Le CCPM recommande au Conseil de r\u00e9it\u00e9rer, tel que le prescrit l\u2019ANACDE, que c\u2019est au Secr\u00e9tariat et non aux Parties qu\u2019appartient principalement la responsabilit\u00e9 d\u2019\u00e9laborer lesdits programme et budget.<\/p>\n<p><strong>4.2<\/strong>\u00a0En ce qui a trait au processus relatif aux communications de citoyens, le CCPM recommande que la proposition charge le Secr\u00e9tariat de prendre des mesures internes afin d\u2019am\u00e9liorer sa rapidit\u00e9 d\u2019ex\u00e9cution dans le cadre de ce processus. Il recommande en outre, dans les r\u00e9f\u00e9rences faites \u00e0 ce processus, de mentionner que, en plus de fournir de l\u2019information sur les m\u00e9thodes d\u2019application des lois, ce processus vise \u00e9galement \u00e0 favoriser l\u2019examen de l\u2019efficacit\u00e9 de l\u2019application des lois de l\u2019environnement des Parties et de toute lacune dans cette application.<\/p>\n<p><strong>4.3<\/strong>\u00a0Le CCPM recommande au Conseil, compte tenu du paragraphe 11(3) de l\u2019ANACDE, de ne pas \u00e9largir son r\u00f4le actuel lui permettant de rejeter la nomination par vote majoritaire de nouveaux employ\u00e9s du Secr\u00e9tariat ou le renouvellement de leur contrat. Il n\u2019y a aucune raison apparente de formuler cette suggestion de changement dans la proposition. Le renouvellement des contrats doit \u00eatre \u00e0 l\u2019unique discr\u00e9tion du directeur ex\u00e9cutif, et ce, en fonction de l\u2019\u00e9valuation qu\u2019il effectue \u00ab en conformit\u00e9 avec les normes g\u00e9n\u00e9rales qui seront \u00e9tablies par le Conseil \u00bb, tel que le prescrit le paragraphe 11(2) de l\u2019ANACDE. Lorsqu\u2019une personne a travaill\u00e9 au Secr\u00e9tariat, il appartient au directeur ex\u00e9cutif, \u00e0 la suggestion des cadres sup\u00e9rieurs, de d\u00e9terminer qui est mieux plac\u00e9 pour \u00e9valuer le rendement de cette personne et de d\u00e9cider s\u2019il faut renouveler son contrat. En revanche, si les Parties prennent part \u00e0 l\u2019examen d\u2019une d\u00e9cision de renouvellement du contrat d\u2019employ\u00e9s du Secr\u00e9tariat, il n\u2019existe aucune disposition pr\u00e9cisant qu\u2019une Partie doive justifier sa d\u00e9cision de refuser un tel renouvellement et aucun moyen en vigueur d\u2019en appeler de cette d\u00e9cision. Dans la pratique, les Parties peuvent prendre une d\u00e9cision pour quelque raison que ce soit, mais cela pr\u00e9sente un risque d\u2019ing\u00e9rence politique dans les d\u00e9cisions des cadres sup\u00e9rieurs du Secr\u00e9tariat. Le fait que le renouvellement des contrats puisse \u00eatre soumis \u00e0 l\u2019examen du Conseil pourrait \u00e9galement susciter des probl\u00e8mes en vertu du paragraphe 11(4) de l\u2019ANACDE, lequel interdit \u00e0 ces cadres de solliciter ou de recevoir des instructions d\u2019aucune entit\u00e9 ext\u00e9rieure au Conseil, y compris un gouvernement. Si le renouvellement du contrat des employ\u00e9s du Secr\u00e9tariat est assujetti \u00e0 une d\u00e9cision des gouvernements, il sera d\u2019autant plus tentant pour les cadres sup\u00e9rieurs de ne pas appliquer \u00e0 la lettre ledit paragraphe 11(4) de l\u2019ANACDE pour se faire bien voir. En dernier lieu, le fait de soumettre ce renouvellement \u00e0 l\u2019approbation du Conseil aura un tr\u00e8s mauvais effet sur le moral des employ\u00e9s du Secr\u00e9tariat. Pour toutes ces raisons, le CCPM conseille instamment que cette suggestion soit retir\u00e9e de la proposition.<\/p>\n<p><strong>5.<\/strong>\u00a0Autres questions<\/p>\n<p><strong>5.1<\/strong>\u00a0Le CCPM est inquiet du fait qu\u2019il existe une confusion entre les Parties et le Conseil dans la proposition, inqui\u00e9tude qu\u2019il a d\u00e9j\u00e0 exprim\u00e9e \u00e0 l\u2019\u00e9gard de l\u2019\u00e9bauche du plan strat\u00e9gique. \u00c0 titre d\u2019exemple, la proposition sugg\u00e8re : \u00ab la fixation d\u2019objectifs de rendement pour le directeur ex\u00e9cutif rel\u00e8verait des Parties \u00bb. Il faudrait mentionner \u00ab du Conseil \u00bb au lieu \u00ab des Parties \u00bb, et ce, conform\u00e9ment aux termes utilis\u00e9s dans l\u2019ensemble de l\u2019article 11 de l\u2019ANACDE.<\/p>\n<p><strong>5.2<\/strong>\u00a0Le CCPM fait \u00e9galement remarquer qu\u2019il serait plus appropri\u00e9 de constituer en annexe ou en document distinct la section de la page 7 de la proposition consacr\u00e9e aux d\u00e9penses, en joignant les modifications propos\u00e9es dans la copie annot\u00e9e ci-jointe, parce que ces questions rel\u00e8vent davantage de la gestion que de la gouvernance.<\/p>\n<p><strong>Les membres du CCPM appuient unanimement le pr\u00e9sent avis au Conseil.<\/strong><\/p>\n<p><strong>Approuv\u00e9 par les membres du CCPM<br \/>\nle 30 novembre 2010<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DISTRIBUTION : G\u00e9n\u00e9rale J\/10-04\/ADV\/Final ORIGINAL : Anglais Objet : \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE. &nbsp; Le Comit\u00e9 consultatif public mixte (CCPM) de la Commission de coop\u00e9ration environnementale (CCE) de l\u2019Am\u00e9rique du Nord; EN CONFORMIT\u00c9\u00a0avec le paragraphe 16(4) de l\u2019Accord nord-am\u00e9ricain de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-22858","documents","type-documents","status-publish","hentry","document_category-avis-au-conseil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE\" \/>\n<meta property=\"og:description\" content=\"DISTRIBUTION : G\u00e9n\u00e9rale J\/10-04\/ADV\/Final ORIGINAL : Anglais Objet : \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE. &nbsp; Le Comit\u00e9 consultatif public mixte (CCPM) de la Commission de coop\u00e9ration environnementale (CCE) de l\u2019Am\u00e9rique du Nord; EN CONFORMIT\u00c9\u00a0avec le paragraphe 16(4) de l\u2019Accord nord-am\u00e9ricain de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T20:20:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\\\/\",\"name\":\"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"datePublished\":\"2010-11-30T05:00:00+00:00\",\"dateModified\":\"2024-07-11T20:20:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"alternateName\":\"CEC - CCA -CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE","og_description":"DISTRIBUTION : G\u00e9n\u00e9rale J\/10-04\/ADV\/Final ORIGINAL : Anglais Objet : \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE. &nbsp; Le Comit\u00e9 consultatif public mixte (CCPM) de la Commission de coop\u00e9ration environnementale (CCE) de l\u2019Am\u00e9rique du Nord; EN CONFORMIT\u00c9\u00a0avec le paragraphe 16(4) de l\u2019Accord nord-am\u00e9ricain de [&hellip;]","og_url":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-07-11T20:20:48+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/","url":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/","name":"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"datePublished":"2010-11-30T05:00:00+00:00","dateModified":"2024-07-11T20:20:48+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/documents\/avis-au-conseil-10-04-ebauche-de-la-proposition-dexamen-de-la-gouvernance-de-la-cce-et-de-la-mise-en-oeuvre-de-lanacde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/www.cec.org\/fr\/documents\/"},{"@type":"ListItem","position":3,"name":"Avis au Conseil 10-04 \u2014 \u00c9bauche de la proposition d\u2019examen de la gouvernance de la CCE et de la mise en \u0153uvre de l\u2019ANACDE"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","alternateName":"CEC - CCA -CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/documents\/22858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/documents"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=22858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}