{"id":22812,"date":"2008-06-26T00:00:00","date_gmt":"2008-06-26T04:00:00","guid":{"rendered":"http:\/\/www.cec.org\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/"},"modified":"2025-11-24T13:55:08","modified_gmt":"2025-11-24T18:55:08","slug":"declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil","status":"publish","type":"documents","link":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/","title":{"rendered":"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil"},"content":{"rendered":"<p><strong>Ottawa (Ontario), Canada, le 26 juin 2008\u00a0<\/strong>- Nous, ministres de l'Environnement du Canada, du Mexique et des \u00c9tats-Unis, membres du Conseil de la Commission de coop\u00e9ration environnementale (CCE), nous sommes r\u00e9unis dans le cadre de notre session ordinaire annuelle le 26 juin 2008 et avons consult\u00e9 le Comit\u00e9 consultatif public mixte (CCPM) et le public \u00e0 cette occasion.<\/p>\n<p>Cette ann\u00e9e marque le quinzi\u00e8me anniversaire des travaux concert\u00e9s entrepris en vertu de l'Accord nord-am\u00e9ricain de coop\u00e9ration dans le domaine de l'environnement (ANACDE), l'accord environnemental parall\u00e8le \u00e0 l'Accord de libre-\u00e9change nord-am\u00e9ricain (AL\u00c9NA). Les r\u00e9sultats que nous avons examin\u00e9s au cours de notre r\u00e9union confirment l'importance que rev\u00eatent ces deux accords, car ils haussent les normes environnementales des trois pays, favorisent une application efficace de la l\u00e9gislation de l'environnement, et renforcent le r\u00f4le des \u00e9changes et du commerce dans la recherche de solutions ax\u00e9es sur les forces du march\u00e9 pour am\u00e9liorer toujours plus la performance environnementale en Am\u00e9rique du Nord. Nous appr\u00e9cions l'examen de l'AL\u00c9NA et de l'environnement qui a r\u00e9v\u00e9l\u00e9 que des occasions sont offertes aux<\/p>\n<p>Parties d'interagir \u00e0 l'\u00e9gard de l'environnement et du commerce.<\/p>\n<p>Les r\u00e9centes r\u00e9alisations dont nous avons pris note aujourd'hui comprennent l'ex\u00e9cution de la directive que nous avons formul\u00e9e en 2007, \u00e0 savoir de dresser des plans de conservation pour pr\u00e9server \u00e0 la fois le monarque et son ph\u00e9nom\u00e8ne migratoire \u00e0 l'\u00e9chelle du continent, et de soutenir la nouvelle strat\u00e9gie dynamique du Mexique consistant \u00e0 prot\u00e9ger le marsouin du golfe de Californie, le mammif\u00e8re marin le plus menac\u00e9 de disparition dans le monde. Par ailleurs, nous avons prescrit au R\u00e9seau nord-am\u00e9ricain d'aires marines prot\u00e9g\u00e9es de se fonder sur les excellents travaux qu'il a accomplis pour jeter les bases d'un processus de conservation du milieu marin en s'effor\u00e7ant d'\u00e9tablir des rapports sur la salubrit\u00e9 de ce milieu \u00e0 l'aide de fiches d'\u00e9valuation des conditions \u00e9cologiques.<\/p>\n<p>Dans nos trois pays, la coop\u00e9ration a \u00e9galement permis d'accomplir des progr\u00e8s notables en r\u00e9duisant les risques que plusieurs substances chimiques dangereuses pr\u00e9sentent pour la sant\u00e9 humaine et la salubrit\u00e9 de l'environnement. Nos efforts ont permis de supprimer ou de r\u00e9duire consid\u00e9rablement la production et l'utilisation en Am\u00e9rique du Nord du DDT, du chlordane, des BPC, du mercure et, plus r\u00e9cemment, du lindane. Nous donnons aujourd'hui une nouvelle orientation \u00e0 la gestion rationnelle d'un plus grand nombre de substances chimiques toxiques et aux secteurs industriels qui les produisent sur l'ensemble du continent. Notre nouveau programme de gestion de ces substances pr\u00e9voit, notamment, l'\u00e9tablissement de rapports am\u00e9lior\u00e9s et comparables sur la production et l'utilisation des substances chimiques, la surveillance environnementale et la biosurveillance humaine, l'\u00e9valuation des \u00e9missions et rejets de substances chimiques \u00e0 l'\u00e9chelle du continent, et la collaboration en vue de r\u00e9duire les risques que pr\u00e9sentent les substances et produits chimiques nouveaux qui suscitent des pr\u00e9occupations communes. Cette strat\u00e9gie am\u00e9lior\u00e9e renforcera la coop\u00e9ration nord-am\u00e9ricaine et r\u00e9pondra directement \u00e0 la n\u00e9cessit\u00e9 de plus en plus manifeste d'une gestion mondiale des substances, tout en donnant suite aux objectifs \u00e9tablis lors du sommet des dirigeants nord-am\u00e9ricains de 2007.<\/p>\n<p>L'accroissement du commerce peut offrir la possibilit\u00e9 d'obtenir des r\u00e9sultats synergiques dans les domaines de l'\u00e9conomie et de l'environnement. Nous reconnaissons toutefois les risques accrus que cela pourrait pr\u00e9senter pour l'environnement, outre le fait qu'une \u00e9troite collaboration s'av\u00e8re essentielle dans un march\u00e9 mondial afin de prot\u00e9ger le public nord-am\u00e9ricain et l'environnement. Nous sommes confront\u00e9s \u00e0 une menace \u00e0 la qualit\u00e9 de l'air et \u00e0 la sant\u00e9 humaine qui prend rapidement de l'ampleur : l'importation et l'utilisation g\u00e9n\u00e9ralis\u00e9e de produits \u00e9quip\u00e9s d'un petit moteur non conforme \u00e0 la r\u00e8glementation. En cons\u00e9quence, nous avons le plaisir d'annoncer que nos agents d'application de la loi travailleront en collaboration dans les domaines des renseignements et du soutien op\u00e9rationnel afin de lutter contre l'importation de tels produits. Nous avons \u00e9galement constat\u00e9 que le IVe Symposium nord-am\u00e9ricain sur l'\u00e9valuation des effets environnementaux du commerce : les services et l'environnement s'est d\u00e9roul\u00e9 de fa\u00e7on fructueuse et que les discussions auxquelles il a donn\u00e9 lieu ont permis d'enrichir les connaissances.<\/p>\n<p>L'Am\u00e9rique du Nord d'aujourd'hui a \u00e9norm\u00e9ment chang\u00e9 par rapport \u00e0 l'\u00e9poque o\u00f9 nos pays sont devenus parties prenantes de l'AL\u00c9NA. Malgr\u00e9 les avantages environnementaux qui ont d\u00e9coul\u00e9 du renforcement de la coop\u00e9ration entre nos pays, il est \u00e9vident que nous ne pourrons progresser en vue de p\u00e9renniser l'environnement que lorsque le secteur priv\u00e9 aura adh\u00e9r\u00e9 aux valeurs et aux objectifs \u00e9cologiques et que ceux-ci feront partie int\u00e9grante du march\u00e9 des produits et services. Nous sommes heureux d'annoncer aujourd'hui l'\u00e9tablissement de partenariats de fournisseurs \u00e9cologiques qui s'\u00e9tendent au secteur nord-am\u00e9ricain de l'automobile, et ce, du Canada jusqu'au Mexique. Il s'agit d'un mouvement particuli\u00e8rement important \u00e9tant donn\u00e9 que les v\u00e9hicules et les pi\u00e8ces automobiles occupent la plus grande place dans le commerce intrar\u00e9gional, et que la sp\u00e9cialisation a contribu\u00e9 \u00e0 l'expansion du commerce depuis 1993.<\/p>\n<p>Nous constatons aussi l'ampleur des travaux que le Secr\u00e9tariat de la CCE a accomplis au cours de l'\u00e9tablissement de son rapport exhaustif sur les d\u00e9bouch\u00e9s et les d\u00e9fis du b\u00e2timent \u00e9cologique en Am\u00e9rique du Nord. Nous avons fait conna\u00eetre les efforts de chacun de nos pays en vue d'inciter leur secteur de la construction \u00e0 am\u00e9liorer le rendement \u00e9nerg\u00e9tique des b\u00e2timents, et notons les tr\u00e8s r\u00e9els avantages environnementaux et la tr\u00e8s grande importance de la poursuite des travaux en vue d'acc\u00e9l\u00e9rer l'implantation du march\u00e9 du b\u00e2timent \u00e9cologique dans la construction et la r\u00e9novation des b\u00e2timents commerciaux et r\u00e9sidentiels en Am\u00e9rique du Nord.<\/p>\n<p>Nous notons \u00e9galement que le Secr\u00e9tariat de la CCE a r\u00e9cemment \u00e9tabli un rapport succinct sur les principales questions connexes \u00e0 l'\u00e9tat de l'environnement, tel que nous le lui avions demand\u00e9 lors de notre derni\u00e8re session ordinaire. En outre, nous nous r\u00e9jouissons des observations que nous recevons r\u00e9guli\u00e8rement, y compris de la part du CCPM, au sujet des tendances environnementales que pourrait conna\u00eetre l'Am\u00e9rique du Nord au cours des prochaines d\u00e9cennies.<\/p>\n<p>Par ailleurs, nous r\u00e9it\u00e9rons notre engagement \u00e0 poursuivre et \u00e0 intensifier les travaux sur les principaux d\u00e9fis environnementaux auxquels est confront\u00e9e l'Am\u00e9rique du Nord, et convenons d'orienter le plan strat\u00e9gique de la CCE pour 2010 \u00e0 2015 et de faire en sorte qu'il soit ax\u00e9 sur des r\u00e9sultats afin d'\u00e9valuer notre degr\u00e9 de r\u00e9ussite d'ann\u00e9e en ann\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ottawa (Ontario), Canada, le 26 juin 2008\u00a0&#8211; Nous, ministres de l&rsquo;Environnement du Canada, du Mexique et des \u00c9tats-Unis, membres du Conseil de la Commission de coop\u00e9ration environnementale (CCE), nous sommes r\u00e9unis dans le cadre de notre session ordinaire annuelle le 26 juin 2008 et avons consult\u00e9 le Comit\u00e9 consultatif public mixte (CCPM) et le public [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-22812","documents","type-documents","status-publish","hentry","document_category-declaration-ministerielle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil\" \/>\n<meta property=\"og:description\" content=\"Ottawa (Ontario), Canada, le 26 juin 2008\u00a0- Nous, ministres de l&#039;Environnement du Canada, du Mexique et des \u00c9tats-Unis, membres du Conseil de la Commission de coop\u00e9ration environnementale (CCE), nous sommes r\u00e9unis dans le cadre de notre session ordinaire annuelle le 26 juin 2008 et avons consult\u00e9 le Comit\u00e9 consultatif public mixte (CCPM) et le public [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/\" \/>\n<meta property=\"og:site_name\" content=\"Commission de coop\u00e9ration environnementale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T18:55:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\\\/\",\"name\":\"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\"},\"datePublished\":\"2008-06-26T04:00:00+00:00\",\"dateModified\":\"2025-11-24T18:55:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/documents\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil","og_description":"Ottawa (Ontario), Canada, le 26 juin 2008\u00a0- Nous, ministres de l'Environnement du Canada, du Mexique et des \u00c9tats-Unis, membres du Conseil de la Commission de coop\u00e9ration environnementale (CCE), nous sommes r\u00e9unis dans le cadre de notre session ordinaire annuelle le 26 juin 2008 et avons consult\u00e9 le Comit\u00e9 consultatif public mixte (CCPM) et le public [&hellip;]","og_url":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/","og_site_name":"Commission de coop\u00e9ration environnementale","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2025-11-24T18:55:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/","url":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/","name":"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil","isPartOf":{"@id":"https:\/\/www.cec.org\/fr\/#website"},"datePublished":"2008-06-26T04:00:00+00:00","dateModified":"2025-11-24T18:55:08+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/fr\/documents\/declaration-ministerielle-de-2008-xve-session-ordinaire-du-conseil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cec.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/www.cec.org\/fr\/documents\/"},{"@type":"ListItem","position":3,"name":"D\u00e9claration minist\u00e9rielle de 2008 \u2014 XVe session ordinaire du Conseil"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/fr\/#website","url":"https:\/\/www.cec.org\/fr\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/fr\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/fr\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/documents\/22812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/types\/documents"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/fr\/wp-json\/wp\/v2\/media?parent=22812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}