{"id":662,"date":"2019-02-26T11:14:58","date_gmt":"2019-02-26T16:14:58","guid":{"rendered":"http:\/\/www.cec.org\/flwm\/?p=662"},"modified":"2022-03-30T16:30:01","modified_gmt":"2022-03-30T20:30:01","slug":"definir-votre-portee","status":"publish","type":"post","link":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/","title":{"rendered":"D\u00e9finir votre port\u00e9e"},"content":{"rendered":"<p>Lorsque vous avez \u00e9tabli qu\u2019il vaut la peine de mesurer la PGA, d\u00e9terminez ce qu\u2019est la PGA dans votre organisation et comment vous allez communiquer cette information, tant \u00e0 l\u2019interne qu\u2019\u00e0 l\u2019ext\u00e9rieur de l\u2019organisation. La communication publique de donn\u00e9es sur la PGA pr\u00e9sente de nombreux avantages\u00a0: elle sensibilise les gens au probl\u00e8me, elle permet un \u00e9change d\u2019information entre entreprises, elle fournit de l\u2019information aux d\u00e9cideurs et elle favorise le suivi de la PGA dans le temps.<\/p>\n<p>Les communications publiques devraient respecter la <em>Food Loss and Waste Accounting and Reporting Standard <\/em>(norme de comptabilisation et de communication de la perte et du gaspillage d\u2019aliments), ou <a href=\"http:\/\/flwprotocol.org\/\"><em>norme sur la PGA<\/em><\/a>. Il s\u2019agit d\u2019une \u00ab\u00a0norme internationale qui d\u00e9finit les exigences et donne des conseils en mati\u00e8re de quantification et de d\u00e9claration du poids des aliments et\/ou des parties non comestibles extraits de la cha\u00eene d\u2019approvisionnement alimentaire\u00a0\u00bb (FLW Protocol, 2016a). La norme clarifie les d\u00e9finitions et montre les destinations possibles des aliments qui sont retir\u00e9s de la cha\u00eene d\u2019approvisionnement alimentaire humaine.<\/p>\n<h2>Suivre les progr\u00e8s de la pr\u00e9vention de la PGA<\/h2>\n<p>La norme sur la PGA ne donne pas de conseils particuliers quant au suivi des progr\u00e8s en mati\u00e8re de pr\u00e9vention, mais on peut faire ce suivi en fixant une ann\u00e9e de r\u00e9f\u00e9rence comme point de d\u00e9part, puis en \u00e9valuant les activit\u00e9s de pr\u00e9vention par rapport \u00e0 cette ann\u00e9e. Si on observe une augmentation ou une diminution de la production totale, un mesurage intensif (tonnes par unit\u00e9 de production) pourra mieux quantifier la PGA \u00e9vit\u00e9e. Par exemple, une entreprise peut fixer 2016 comme ann\u00e9e de r\u00e9f\u00e9rence, ann\u00e9e o\u00f9 elle a comptabilis\u00e9 15\u00a0000\u00a0tonnes de PGA. L\u2019ann\u00e9e suivante, la PGA pourrait totaliser 13\u00a0500\u00a0tonnes, ce qui signifierait qu\u2019elle a \u00e9vit\u00e9 1\u00a0500\u00a0tonnes de PGA.<\/p>\n<p>Le tableau\u00a02 pr\u00e9sente un exemple hypoth\u00e9tique d\u2019une fa\u00e7on de faire le suivi de la pr\u00e9vention parall\u00e8lement au suivi des quantit\u00e9s de PGA.<\/p>\n<p><strong>Tableau 2. Suivi de la r\u00e9duction de la PGA gr\u00e2ce \u00e0 la mesure des d\u00e9chets alimentaires envoy\u00e9s \u00e0 diverses destinations au fil du temps (tonnes\/ann\u00e9e)<\/strong><\/p>\n<table class=\"complex-table\" border=\"0\" width=\"100%\">\n<tbody>\n<tr>\n<th valign=\"top\" width=\"25%\"><strong>\u00a0<\/strong><\/th>\n<th valign=\"top\" width=\"25%\"><strong>2016<\/strong><\/th>\n<th valign=\"top\" width=\"25%\"><strong>2017<\/strong><\/th>\n<th valign=\"top\" width=\"25%\"><strong>2018<\/strong><\/th>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Production totale<\/strong><\/td>\n<td valign=\"top\">100\u00a0000 tonnes<\/td>\n<td valign=\"top\">100\u00a0000 tonnes<\/td>\n<td valign=\"top\">100\u00a0000 tonnes<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Digestion ana\u00e9robie<\/td>\n<td valign=\"top\">3\u00a0000 tonnes<\/td>\n<td valign=\"top\">4\u00a0000 tonnes<\/td>\n<td valign=\"top\">4\u00a0000 tonnes<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Enfouissement<\/td>\n<td valign=\"top\">8\u00a0000 tonnes<\/td>\n<td valign=\"top\">6\u00a0000 tonnes<\/td>\n<td valign=\"top\">5\u00a0500 tonnes<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\u00c9limination \u00e0 l\u2019\u00e9gout<\/td>\n<td valign=\"top\">4\u00a0000 tonnes<\/td>\n<td valign=\"top\">3\u00a0500 tonnes<\/td>\n<td valign=\"top\">3\u00a0500 tonnes<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>PGA totale<\/strong><\/td>\n<td valign=\"top\"><strong>15\u00a0000 tonnes<\/strong><\/td>\n<td valign=\"top\"><strong>13\u00a0500 tonnes<\/strong><\/td>\n<td valign=\"top\"><strong>13\u00a0000 tonnes<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Tonnes de d\u00e9chets alimentaires par unit\u00e9 de production (pourcentage)<\/td>\n<td valign=\"top\">15\u00a0%<\/td>\n<td valign=\"top\">13,5\u00a0%<\/td>\n<td valign=\"top\">13\u00a0%<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>R\u00e9duction de la PGA (en pourcentage par rapport \u00e0 2016)<\/strong><\/td>\n<td valign=\"top\"><strong>0\u00a0%<\/strong><\/td>\n<td valign=\"top\"><strong>-10\u00a0%<\/strong><\/td>\n<td valign=\"top\"><strong>-13\u00a0%<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Source\u00a0: Auteurs.<\/p>\n<h2>D\u00e9claration des quantit\u00e9s de d\u00e9chets alimentaires<\/h2>\n<p>Les d\u00e9clarations conformes \u00e0 la norme sur la PGA n\u00e9cessitent l\u2019\u00e9tablissement de la \u00ab\u00a0port\u00e9e\u00a0\u00bb de votre PGA, comme l\u2019illustre la figure 2. Cette port\u00e9e comprend seulement les aliments qui ont \u00e9t\u00e9 retir\u00e9s de la cha\u00eene d\u2019approvisionnement alimentaire humaine, ce qui signifie que la nourriture donn\u00e9e, redistribu\u00e9e ou autrement conserv\u00e9e dans cette cha\u00eene est exclue. Le suivi de la redistribution de nourriture peut aller dans le sens de vos objectifs et \u00eatre effectu\u00e9 selon une m\u00e9thode similaire \u00e0 celle d\u00e9crite dans la section \u00ab\u00a0Suivre le progr\u00e8s de la pr\u00e9vention de la PGA\u00a0\u00bb.<\/p>\n<p><strong>Figure\u00a0 2. Port\u00e9e d\u2019un inventaire de la PGA<\/strong><\/p>\n<p>La port\u00e9e comporte quatre \u00e9l\u00e9ments\u00a0: calendrier, type de mati\u00e8re, destination et limite.<\/p>\n<h3>Calendrier<\/h3>\n<p>D\u00e9terminer la p\u00e9riode vis\u00e9e par la d\u00e9claration des r\u00e9sultats de l\u2019inventaire. Ces r\u00e9sultats sont g\u00e9n\u00e9ralement communiqu\u00e9s annuellement.<\/p>\n<h3>Type de mati\u00e8re<\/h3>\n<p>D\u00e9terminer les mati\u00e8res incluses dans l\u2019inventaire\u00a0: nourriture seulement, parties non comestibles seulement ou les deux. Les parties non comestibles sont d\u00e9finies comme les parties d\u2019un produit alimentaire qui ne sont pas destin\u00e9es \u00e0 la consommation, comme les os, les pelures ou les noyaux.<\/p>\n<h3>Destination<\/h3>\n<p>La destination correspond \u00e0 l\u2019endroit o\u00f9 sont envoy\u00e9s les aliments qui sont retir\u00e9s de la cha\u00eene d\u2019approvisionnement alimentaire. Les dix cat\u00e9gories de destinations d\u00e9crites dans la norme sur la PGA sont d\u00e9finies au tableau 3. Les destinations n\u2019incluent pas la pr\u00e9vention de la PGA ou les aliments qui sont redistribu\u00e9s, dont le suivi peut \u00eatre fait tel que d\u00e9crit dans la section \u00ab\u00a0<a href=\"#_Reporting_on_Prevention\">Suivre les progr\u00e8s de la pr\u00e9vention de la PGA<\/a>\u00a0\u00bb. La nourriture distribu\u00e9e pour consommation humaine \u00e0 l\u2019ext\u00e9rieur du march\u00e9 n\u2019est pas consid\u00e9r\u00e9e comme perdue ou gaspill\u00e9e, puisqu\u2019elle n\u2019est pas envoy\u00e9e \u00e0 une destination.<\/p>\n<p><strong>Tableau 3. D\u00e9finition des destinations des d\u00e9chets alimentaires selon la norme sur la PGA<\/strong><\/p>\n<table class=\"complex-table\" border=\"0\" width=\"100%\">\n<tbody>\n<tr>\n<th valign=\"top\" width=\"30%\"><strong>Destination<\/strong><\/th>\n<th valign=\"top\" width=\"70%\"><strong>D\u00e9finition<\/strong><\/th>\n<\/tr>\n<tr>\n<td valign=\"top\">Nourriture pour animaux<\/td>\n<td valign=\"top\">Les mati\u00e8res sont retir\u00e9es de la cha\u00eene d\u2019approvisionnement alimentaire et r\u00e9achemin\u00e9es vers le secteur animal<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Mat\u00e9riaux biologiques\/transformation biochimique<\/td>\n<td valign=\"top\">Conversion des mati\u00e8res en produits industriels<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Codigestion\/digestion ana\u00e9robie<\/td>\n<td valign=\"top\">D\u00e9composition des mati\u00e8res \u00e0 l\u2019aide de bact\u00e9ries, en l\u2019absence d\u2019oxyg\u00e8ne<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Compostage\/proc\u00e9d\u00e9 a\u00e9robie<\/td>\n<td valign=\"top\">D\u00e9composition des mati\u00e8res \u00e0 l\u2019aide de bact\u00e9ries, dans un environnement riche en oxyg\u00e8ne<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Combustion \u00a0contr\u00f4l\u00e9e<\/td>\n<td valign=\"top\">Effectu\u00e9e dans une installation con\u00e7ue express\u00e9ment pour br\u00fbler des r\u00e9sidus dans des conditions contr\u00f4l\u00e9es<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Application sur les terres<\/td>\n<td valign=\"top\">\u00c9pandage, vaporisation, injection ou ajout de mati\u00e8res organiques sur ou sous la surface de la terre pour enrichir le sol<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Enfouissement<\/td>\n<td valign=\"top\">Sur un terrain ou dans un site excav\u00e9 con\u00e7u pr\u00e9cis\u00e9ment pour recevoir des d\u00e9chets<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Non r\u00e9colt\u00e9s\/retourn\u00e9s \u00e0 la terre<\/td>\n<td valign=\"top\">Les produits qui \u00e9taient pr\u00eats pour la r\u00e9colte sont laiss\u00e9s dans les champs ou labour\u00e9s dans le sol<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">D\u00e9chets\/rejets\/ordures<\/td>\n<td valign=\"top\">Mati\u00e8res abandonn\u00e9es sur la terre ou jet\u00e9es \u00e0 la mer<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\u00c9limination \u00e0 l\u2019\u00e9gout<\/td>\n<td valign=\"top\">Mati\u00e8res rejet\u00e9es \u00e0 l\u2019\u00e9gout, avec ou sans traitement pr\u00e9alable<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Autre<\/td>\n<td valign=\"top\">Mati\u00e8res envoy\u00e9es ailleurs qu\u2019aux dix destinations ci-dessus<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Source\u00a0: FLW Protocol, 2016a<\/p>\n<p>La nourriture r\u00e9cup\u00e9r\u00e9e et envoy\u00e9e \u00e0 des organismes qui nourrissent les personnes d\u00e9favoris\u00e9es n\u2019est habituellement pas consid\u00e9r\u00e9e comme de la PGA et n\u2019est par cons\u00e9quent pas identifi\u00e9e comme destination \u00e0 la figure\u00a02. Certaines organisations pourraient \u00e9galement exclure la nourriture pour animaux et la transformation en mat\u00e9riaux biologiques\/biochimiques (o\u00f9 la mati\u00e8re est transform\u00e9e en produits industriels) de leur d\u00e9finition de la PGA.<\/p>\n<p>Bien que les d\u00e9finitions et la port\u00e9e de la PGA puissent varier, il est n\u00e9anmoins important de mesurer toutes les destinations finales possibles des aliments r\u00e9cup\u00e9r\u00e9s et des aliments perdus ou gaspill\u00e9s, afin de justifier les activit\u00e9s men\u00e9es pour r\u00e9duire au minimum les inefficacit\u00e9s op\u00e9rationnelles.<\/p>\n<h3>Limite<\/h3>\n<p>Cet \u00e9l\u00e9ment comporte quatre composantes\u00a0:<\/p>\n<ul>\n<li>La <em>cat\u00e9gorie d\u2019aliments<\/em>, ou les types d\u2019aliments inclus dans l\u2019inventaire;<\/li>\n<li>L\u2019<em>\u00e9tape du cycle de vie<\/em>, ou les \u00e9tapes de la cha\u00eene d\u2019approvisionnement alimentaire (p.\u00a0ex., transformation et fabrication, vente au d\u00e9tail) incluses dans l\u2019inventaire;<\/li>\n<li>La <em>g\u00e9ographie,<\/em> ou les limites g\u00e9ographiques \u00e0 l\u2019int\u00e9rieur desquelles l\u2019inventaire est effectu\u00e9;<\/li>\n<li>L\u2019<em>organisation,<\/em> ou le type d\u2019unit\u00e9 (p. ex., m\u00e9nage ou usine) o\u00f9 la PGA se produit.<\/li>\n<\/ul>\n<h2>Importance de la port\u00e9e<\/h2>\n<p>Il importe de communiquer la port\u00e9e d\u2019un inventaire, parce qu\u2019il existe de nombreuses d\u00e9finitions du concept de \u00ab\u00a0perte et gaspillage d\u2019aliments\u00a0\u00bb. Dans certains cas, les aliments sont inclus, mais pas les parties non comestibles, tandis que dans d\u2019autres, seul un sous-ensemble des destinations possibles est pris en compte. En faisant conna\u00eetre la port\u00e9e d\u2019un inventaire, une entreprise ou un gouvernement clarifie sa d\u00e9finition de la PGA et permet ainsi des comparaisons et un suivi plus exacts de la PGA dans le temps.<\/p>\n<h2>Autres ressources pour la d\u00e9claration<\/h2>\n<p>La <a href=\"http:\/\/flwprotocol.org\/wp-content\/uploads\/2017\/05\/FLW_Standard_final_2016.pdf\"><em>norme sur la PGA<\/em><\/a> propose un certain nombre de ressources. Le <a href=\"http:\/\/flwprotocol.org\/wp-content\/uploads\/2017\/05\/FLW_Standard_final_2016.pdf#page=36\">chapitre 6<\/a> explique comment \u00e9tablir la port\u00e9e, tandis que le <a href=\"http:\/\/flwprotocol.org\/wp-content\/uploads\/2017\/05\/FLW_Standard_final_2016.pdf#page=102\">chapitre 13<\/a> donne d\u2019autres conseils pour la d\u00e9claration. Vous pouvez \u00e9galement t\u00e9l\u00e9charger un <a href=\"http:\/\/flwprotocol.org\/wp-content\/uploads\/2016\/05\/FLW-Standard-Inventory-Reporting-Template_June-2016_update-2.xlsm\">mod\u00e8le de formulaire de d\u00e9claration<\/a> et <a href=\"http:\/\/flwprotocol.org\/wp-content\/uploads\/2017\/06\/Template_FLW-Standard-Visual-Representation-of-Inventory-Scope_2017_June.pptx\">un mod\u00e8le personnalisable d\u2019\u00e9tablissement de la port\u00e9e<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque vous avez \u00e9tabli qu\u2019il vaut la peine de mesurer la PGA, d\u00e9terminez ce qu\u2019est la PGA dans votre organisation et comment vous allez communiquer cette information, tant \u00e0 l\u2019interne qu\u2019\u00e0 l\u2019ext\u00e9rieur de l\u2019organisation. La communication publique de donn\u00e9es sur la PGA pr\u00e9sente de nombreux avantages\u00a0: elle sensibilise les gens au probl\u00e8me, elle permet un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-checklist-item-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA\" \/>\n<meta property=\"og:description\" content=\"Lorsque vous avez \u00e9tabli qu\u2019il vaut la peine de mesurer la PGA, d\u00e9terminez ce qu\u2019est la PGA dans votre organisation et comment vous allez communiquer cette information, tant \u00e0 l\u2019interne qu\u2019\u00e0 l\u2019ext\u00e9rieur de l\u2019organisation. La communication publique de donn\u00e9es sur la PGA pr\u00e9sente de nombreux avantages\u00a0: elle sensibilise les gens au probl\u00e8me, elle permet un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/\" \/>\n<meta property=\"og:site_name\" content=\"Pourquoi et comment mesurer la PGA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-26T16:14:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T20:30:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"flwm_adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CECweb\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"flwm_adm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/\"},\"author\":{\"name\":\"flwm_adm\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#\\\/schema\\\/person\\\/1c10897b20fc5b1151c55ee181c7a79c\"},\"headline\":\"D\u00e9finir votre port\u00e9e\",\"datePublished\":\"2019-02-26T16:14:58+00:00\",\"dateModified\":\"2022-03-30T20:30:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/\"},\"wordCount\":1390,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Scope.webp\",\"articleSection\":[\"\u00c9l\u00e9ment de la liste de contr\u00f4le\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/\",\"name\":\"D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Scope.webp\",\"datePublished\":\"2019-02-26T16:14:58+00:00\",\"dateModified\":\"2022-03-30T20:30:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Scope.webp\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Scope.webp\",\"width\":1900,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/checklist-item-fr\\\/definir-votre-portee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9finir votre port\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/\",\"name\":\"Why and How to Measure Food Loss and Waste\",\"description\":\"Utilisez notre calculateur des co\u00fbts pour l\u2019entreprise afin d\u2019\u00e9valuer votre PGA, inspirez-vous des \u00e9tudes de cas relatives \u00e0 nos partenaires et passez \u00e0 l\u2019action!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"url\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"http:\\\/\\\/www.cec.org\\\/flwm\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/mycompany\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/cecweb.medium.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/#\\\/schema\\\/person\\\/1c10897b20fc5b1151c55ee181c7a79c\",\"name\":\"flwm_adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"caption\":\"flwm_adm\"},\"url\":\"https:\\\/\\\/www.cec.org\\\/flwm\\\/fr\\\/author\\\/flwm_adm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA","og_description":"Lorsque vous avez \u00e9tabli qu\u2019il vaut la peine de mesurer la PGA, d\u00e9terminez ce qu\u2019est la PGA dans votre organisation et comment vous allez communiquer cette information, tant \u00e0 l\u2019interne qu\u2019\u00e0 l\u2019ext\u00e9rieur de l\u2019organisation. La communication publique de donn\u00e9es sur la PGA pr\u00e9sente de nombreux avantages\u00a0: elle sensibilise les gens au probl\u00e8me, elle permet un [&hellip;]","og_url":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/","og_site_name":"Pourquoi et comment mesurer la PGA","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_published_time":"2019-02-26T16:14:58+00:00","article_modified_time":"2022-03-30T20:30:01+00:00","og_image":[{"width":1900,"height":1200,"url":"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp","type":"image\/webp"}],"author":"flwm_adm","twitter_card":"summary_large_image","twitter_creator":"@CECweb","twitter_site":"@CECweb","twitter_misc":{"\u00c9crit par":"flwm_adm","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#article","isPartOf":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/"},"author":{"name":"flwm_adm","@id":"https:\/\/www.cec.org\/flwm\/fr\/#\/schema\/person\/1c10897b20fc5b1151c55ee181c7a79c"},"headline":"D\u00e9finir votre port\u00e9e","datePublished":"2019-02-26T16:14:58+00:00","dateModified":"2022-03-30T20:30:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/"},"wordCount":1390,"publisher":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/#organization"},"image":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp","articleSection":["\u00c9l\u00e9ment de la liste de contr\u00f4le"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/","url":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/","name":"D\u00e9finir votre port\u00e9e - Pourquoi et comment mesurer la PGA","isPartOf":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp","datePublished":"2019-02-26T16:14:58+00:00","dateModified":"2022-03-30T20:30:01+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#primaryimage","url":"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp","contentUrl":"https:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/05\/Scope.webp","width":1900,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/flwm\/fr\/checklist-item-fr\/definir-votre-portee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cec.org\/flwm\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9finir votre port\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/flwm\/fr\/#website","url":"https:\/\/www.cec.org\/flwm\/fr\/","name":"Why and How to Measure Food Loss and Waste","description":"Utilisez notre calculateur des co\u00fbts pour l\u2019entreprise afin d\u2019\u00e9valuer votre PGA, inspirez-vous des \u00e9tudes de cas relatives \u00e0 nos partenaires et passez \u00e0 l\u2019action!","publisher":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/flwm\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/flwm\/fr\/#organization","name":"Commission for Environmental Cooperation","url":"https:\/\/www.cec.org\/flwm\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cec.org\/flwm\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/08\/CEC-Logo-RGB.png","contentUrl":"http:\/\/www.cec.org\/flwm\/wp-content\/uploads\/2023\/08\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/flwm\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/mycompany\/","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/cecweb.medium.com\/","https:\/\/www.youtube.com\/user\/CECweb"]},{"@type":"Person","@id":"https:\/\/www.cec.org\/flwm\/fr\/#\/schema\/person\/1c10897b20fc5b1151c55ee181c7a79c","name":"flwm_adm","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","caption":"flwm_adm"},"url":"https:\/\/www.cec.org\/flwm\/fr\/author\/flwm_adm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/posts\/662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/comments?post=662"}],"version-history":[{"count":4,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/posts\/662\/revisions"}],"predecessor-version":[{"id":683,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/posts\/662\/revisions\/683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/media\/1896"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/media?parent=662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/categories?post=662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cec.org\/flwm\/fr\/wp-json\/wp\/v2\/tags?post=662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}