{"id":57814,"date":"2025-02-24T13:01:42","date_gmt":"2025-02-24T18:01:42","guid":{"rendered":"http:\/\/www.cec.org\/speaker\/john-jackson\/"},"modified":"2025-02-24T13:01:42","modified_gmt":"2025-02-24T18:01:42","slug":"john-jackson","status":"publish","type":"speaker","link":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/","title":{"rendered":"John Jackson"},"content":{"rendered":"<p><strong>John Jackson<\/strong> ha trabajado con grupos de ciudadanos durante m\u00e1s de 50 a\u00f1os, ayud\u00e1ndolos a organizarse en torno a problem\u00e1ticas como sustancias t\u00f3xicas, gesti\u00f3n de residuos, niveles de agua y conservaci\u00f3n, especialmente centrados en los Grandes Lagos de Am\u00e9rica del Norte y la cuenca del r\u00edo San Lorenzo. Gran parte de su trabajo se relaciona con el derecho a la informaci\u00f3n de la comunidad, por ejemplo: investigando la legislaci\u00f3n sobre el derecho a la informaci\u00f3n en todo el mundo; dise\u00f1ando estatutos sobre el derecho a la informaci\u00f3n para las ciudades de Windsor y Toronto (Ontario); y ayudando a los grupos de ciudadanos a utilizar disposiciones de derecho a la informaci\u00f3n para proteger a sus comunidades de las amenazas t\u00f3xicas. Ha participado en el comit\u00e9 multiparte establecido por el gobierno canadiense para desarrollar su programa RETC, el Inventario Nacional de Emisiones de Contaminantes (NPRI), y ha formado parte del comit\u00e9 asesor del NPRI durante los \u00faltimos 40 a\u00f1os. John es presidente de la Red de Ecorregi\u00f3n de los Grandes Lagos, una coalici\u00f3n transnacional de ciudadanos de Canad\u00e1 y Estados Unidos que trabajan para proteger y restaurar los Grandes Lagos. Tambi\u00e9n es coordinador de la Red Ciudadana para la Gesti\u00f3n de Residuos, copresidente de la Red Binacional Grandes Lagos Libres de T\u00f3xicos, y miembro de la junta directiva de la Asociaci\u00f3n Canadiense de Derecho Ambiental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>John Jackson ha trabajado con grupos de ciudadanos durante m\u00e1s de 50 a\u00f1os, ayud\u00e1ndolos a organizarse en torno a problem\u00e1ticas como sustancias t\u00f3xicas, gesti\u00f3n de residuos, niveles de agua y conservaci\u00f3n, especialmente centrados en los Grandes Lagos de Am\u00e9rica del Norte y la cuenca del r\u00edo San Lorenzo. Gran parte de su trabajo se relaciona [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-57814","speaker","type-speaker","status-publish","hentry","country-canada-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>John Jackson &#8211; Comisi\u00f3n para la Cooperaci\u00f3n Ambiental<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Jackson\" \/>\n<meta property=\"og:description\" content=\"John Jackson ha trabajado con grupos de ciudadanos durante m\u00e1s de 50 a\u00f1os, ayud\u00e1ndolos a organizarse en torno a problem\u00e1ticas como sustancias t\u00f3xicas, gesti\u00f3n de residuos, niveles de agua y conservaci\u00f3n, especialmente centrados en los Grandes Lagos de Am\u00e9rica del Norte y la cuenca del r\u00edo San Lorenzo. Gran parte de su trabajo se relaciona [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/speaker\\\/john-jackson\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/speaker\\\/john-jackson\\\/\",\"name\":\"John Jackson &#8211; Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"datePublished\":\"2025-02-24T18:01:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/speaker\\\/john-jackson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/speaker\\\/john-jackson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/speaker\\\/john-jackson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John Jackson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"John Jackson &#8211; Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"John Jackson","og_description":"John Jackson ha trabajado con grupos de ciudadanos durante m\u00e1s de 50 a\u00f1os, ayud\u00e1ndolos a organizarse en torno a problem\u00e1ticas como sustancias t\u00f3xicas, gesti\u00f3n de residuos, niveles de agua y conservaci\u00f3n, especialmente centrados en los Grandes Lagos de Am\u00e9rica del Norte y la cuenca del r\u00edo San Lorenzo. Gran parte de su trabajo se relaciona [&hellip;]","og_url":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/","url":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/","name":"John Jackson &#8211; Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"datePublished":"2025-02-24T18:01:42+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/speaker\/john-jackson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/speaker\/john-jackson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"John Jackson"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/speaker\/57814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/speaker"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/speaker"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=57814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}