{"id":44236,"date":"1997-01-01T00:00:00","date_gmt":"1997-01-01T05:00:00","guid":{"rendered":"http:\/\/www.cec.org\/publications\/rutas-continentales-de-los-contaminantes\/"},"modified":"2024-07-11T16:49:31","modified_gmt":"2024-07-11T20:49:31","slug":"rutas-continentales-de-los-contaminantes","status":"publish","type":"publications","link":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/","title":{"rendered":"Rutas continentales de los contaminantes"},"content":{"rendered":"<p>Se consider\u00f3 que uno de esos asuntos es el transporte en el aire a grandes distancias de diversos conta-minantes persistentes, motivo de preocupaci\u00f3n en Am\u00e9rica del Norte (las rutas continentales de los contaminantes). Por ello, a iniciativa del Secretariado de la CCA, se acord\u00f3 la creaci\u00f3n de un Comit\u00e9 Asesor de Expertos para que estudiara el problema. El presente documento se elabor\u00f3 con base en el informe que produjo dicho Comit\u00e9. La iniciativa del Secretariado procedi\u00f3 en t\u00e9rminos del Art\u00edculo 13 del ACAAN, que le autoriza a elaborar informes al Consejo sobre aspectos comprendidos en el programa de trabajo anual de la CCA. Con la aprobaci\u00f3n del Consejo, este informe se pone ahora a disposici\u00f3n del p\u00fablico, con la esperanza de que las recomendaciones que contiene alienten la cooperaci\u00f3n trilateral en este asunto espec\u00edfico. El informe res-ponde a las inquietudes de la poblaci\u00f3n por el empeoramiento de la calidad del aire y sugiere oportunidades para enriquecer el desarrollo de una estrategia conjunta frente a la contaminaci\u00f3n atmosf\u00e9rica en Am\u00e9rica del Norte desde una perspectiva transfronteriza y regional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Acuerdo de Cooperaci\u00f3n Ambiental de Am\u00e9rica del Norte (ACAAN) entr\u00f3 en vigor junto con el Tratado de Libre Comercio (TLC) el 1 de enero de 1994. El ACAAN se negoci\u00f3 con objeto de establecer un marco de referencia para la cooperaci\u00f3n ambiental regional, atender las preocupaciones en torno a los efectos potenciales de la liberalizaci\u00f3n del comercio y de la creciente integraci\u00f3n econ\u00f3mica en el medio ambiente de Am\u00e9rica del Norte, as\u00ed como fomentar una agenda de cooperaci\u00f3n ambiental entre los tres pa\u00edses en asuntos de importancia regional e inter\u00e9s mutuo.<\/p>\n","protected":false},"featured_media":39217,"template":"","class_list":["post-44236","publications","type-publications","status-publish","has-post-thumbnail","hentry","document_type-informe-independiente-del-secretariado","document_theme-contaminantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rutas continentales de los contaminantes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rutas continentales de los contaminantes\" \/>\n<meta property=\"og:description\" content=\"El Acuerdo de Cooperaci\u00f3n Ambiental de Am\u00e9rica del Norte (ACAAN) entr\u00f3 en vigor junto con el Tratado de Libre Comercio (TLC) el 1 de enero de 1994. El ACAAN se negoci\u00f3 con objeto de establecer un marco de referencia para la cooperaci\u00f3n ambiental regional, atender las preocupaciones en torno a los efectos potenciales de la liberalizaci\u00f3n del comercio y de la creciente integraci\u00f3n econ\u00f3mica en el medio ambiente de Am\u00e9rica del Norte, as\u00ed como fomentar una agenda de cooperaci\u00f3n ambiental entre los tres pa\u00edses en asuntos de importancia regional e inter\u00e9s mutuo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T20:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png\" \/>\n\t<meta property=\"og:image:width\" content=\"465\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/\",\"name\":\"Rutas continentales de los contaminantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png\",\"datePublished\":\"1997-01-01T05:00:00+00:00\",\"dateModified\":\"2024-07-11T20:49:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png\",\"width\":465,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/rutas-continentales-de-los-contaminantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaciones\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/publicaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rutas continentales de los contaminantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rutas continentales de los contaminantes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/","og_locale":"es_ES","og_type":"article","og_title":"Rutas continentales de los contaminantes","og_description":"El Acuerdo de Cooperaci\u00f3n Ambiental de Am\u00e9rica del Norte (ACAAN) entr\u00f3 en vigor junto con el Tratado de Libre Comercio (TLC) el 1 de enero de 1994. El ACAAN se negoci\u00f3 con objeto de establecer un marco de referencia para la cooperaci\u00f3n ambiental regional, atender las preocupaciones en torno a los efectos potenciales de la liberalizaci\u00f3n del comercio y de la creciente integraci\u00f3n econ\u00f3mica en el medio ambiente de Am\u00e9rica del Norte, as\u00ed como fomentar una agenda de cooperaci\u00f3n ambiental entre los tres pa\u00edses en asuntos de importancia regional e inter\u00e9s mutuo.","og_url":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-07-11T20:49:31+00:00","og_image":[{"width":465,"height":600,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/","url":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/","name":"Rutas continentales de los contaminantes","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png","datePublished":"1997-01-01T05:00:00+00:00","dateModified":"2024-07-11T20:49:31+00:00","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/1617-continental-pollutant-pathways-agenda-cooperation-address-long-range-transport-es.png","width":465,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/publicaciones\/rutas-continentales-de-los-contaminantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Publicaciones","item":"https:\/\/www.cec.org\/es\/publicaciones\/"},{"@type":"ListItem","position":3,"name":"Rutas continentales de los contaminantes"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/publications\/44236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/publications"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/39217"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=44236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}