{"id":11746,"date":"2009-10-18T17:29:59","date_gmt":"2009-10-18T21:29:59","guid":{"rendered":"http:\/\/www.cec.org\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/"},"modified":"2026-08-25T16:54:11","modified_gmt":"2026-08-25T20:54:11","slug":"mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte","status":"publish","type":"post","link":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/","title":{"rendered":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte"},"content":{"rendered":"<p>En la alianza con el sector automotriz, la CCA propone un enfoque distinto: actuar como catalizador para la colaboraci\u00f3n entre iniciativas relacionadas en los tres pa\u00edses. En vista del alto grado de integraci\u00f3n econ\u00f3mica de las cadenas de abasto para la fabricaci\u00f3n de autom\u00f3viles entre las Partes del TLCAN, resulta clara la pertinencia l\u00f3gica de seguir una estrategia integrada para el mejoramiento ambiental de las cadenas de abasto y, con ello, del desempe\u00f1o ambiental general de la industria automotriz de Am\u00e9rica del Norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la alianza con el sector automotriz, la CCA propone un enfoque distinto: actuar como catalizador para la colaboraci\u00f3n entre iniciativas relacionadas en los tres pa\u00edses. En vista del alto grado de integraci\u00f3n econ\u00f3mica de las cadenas de abasto para la fabricaci\u00f3n de autom\u00f3viles entre las Partes del TLCAN, resulta clara la pertinencia l\u00f3gica de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-11746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-economias-sustentables","status-concluido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte<\/title>\n<meta name=\"description\" content=\"Mejoramiento ambiental de las cadenas de abasto y, con ello, del desempe\u00f1o ambiental general de la industria automotriz de Am\u00e9rica del Norte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte\" \/>\n<meta property=\"og:description\" content=\"En la alianza con el sector automotriz, la CCA propone un enfoque distinto: actuar como catalizador para la colaboraci\u00f3n entre iniciativas relacionadas en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-18T21:29:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T20:54:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cecmain_adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CECweb\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/\"},\"author\":{\"name\":\"cecmain_adm\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/person\\\/cfaad09db438c516cb646ff4ea6f47bd\"},\"headline\":\"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte\",\"datePublished\":\"2009-10-18T21:29:59+00:00\",\"dateModified\":\"2026-08-25T20:54:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_greening_na.png\",\"articleSection\":[\"Vida y Econom\u00edas Sustentables\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/\",\"name\":\"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_greening_na.png\",\"datePublished\":\"2009-10-18T21:29:59+00:00\",\"dateModified\":\"2026-08-25T20:54:11+00:00\",\"description\":\"Mejoramiento ambiental de las cadenas de abasto y, con ello, del desempe\u00f1o ambiental general de la industria automotriz de Am\u00e9rica del Norte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_greening_na.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_greening_na.png\",\"width\":600,\"height\":342,\"caption\":\"CEC Projects - Highway with traffic\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/person\\\/cfaad09db438c516cb646ff4ea6f47bd\",\"name\":\"cecmain_adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"caption\":\"cecmain_adm\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte","description":"Mejoramiento ambiental de las cadenas de abasto y, con ello, del desempe\u00f1o ambiental general de la industria automotriz de Am\u00e9rica del Norte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/","og_locale":"es_ES","og_type":"article","og_title":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte","og_description":"En la alianza con el sector automotriz, la CCA propone un enfoque distinto: actuar como catalizador para la colaboraci\u00f3n entre iniciativas relacionadas en","og_url":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_published_time":"2009-10-18T21:29:59+00:00","article_modified_time":"2026-08-25T20:54:11+00:00","og_image":[{"width":600,"height":342,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png","type":"image\/png"}],"author":"cecmain_adm","twitter_card":"summary_large_image","twitter_creator":"@CECweb","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#article","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/"},"author":{"name":"cecmain_adm","@id":"https:\/\/www.cec.org\/es\/#\/schema\/person\/cfaad09db438c516cb646ff4ea6f47bd"},"headline":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte","datePublished":"2009-10-18T21:29:59+00:00","dateModified":"2026-08-25T20:54:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/"},"wordCount":103,"publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"image":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png","articleSection":["Vida y Econom\u00edas Sustentables"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/","url":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/","name":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png","datePublished":"2009-10-18T21:29:59+00:00","dateModified":"2026-08-25T20:54:11+00:00","description":"Mejoramiento ambiental de las cadenas de abasto y, con ello, del desempe\u00f1o ambiental general de la industria automotriz de Am\u00e9rica del Norte.","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_greening_na.png","width":600,"height":342,"caption":"CEC Projects - Highway with traffic"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/mejoramiento-ambiental-de-la-industria-automotriz-de-america-del-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Mejoramiento ambiental de la industria automotriz de Am\u00e9rica del Norte"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"},{"@type":"Person","@id":"https:\/\/www.cec.org\/es\/#\/schema\/person\/cfaad09db438c516cb646ff4ea6f47bd","name":"cecmain_adm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","caption":"cecmain_adm"}}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/comments?post=11746"}],"version-history":[{"count":3,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11746\/revisions"}],"predecessor-version":[{"id":49394,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11746\/revisions\/49394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/4606"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=11746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/categories?post=11746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/tags?post=11746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}