{"id":11745,"date":"2010-10-18T17:29:59","date_gmt":"2010-10-18T21:29:59","guid":{"rendered":"http:\/\/www.cec.org\/evaluacion-ambiental-del-tlcan\/"},"modified":"2025-06-16T18:07:55","modified_gmt":"2025-06-16T22:07:55","slug":"evaluacion-ambiental-del-tlcan","status":"publish","type":"post","link":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/","title":{"rendered":"Evaluaci\u00f3n ambiental del TLCAN"},"content":{"rendered":"<p>La evaluaci\u00f3n ambiental permanente del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales del TLCAN y se ampliar\u00e1 la comprensi\u00f3n de los v\u00ednculos entre medio ambiente y comercio para promover la coherencia de las pol\u00edticas, a escala tanto nacional como regional, en Am\u00e9rica del Norte. El proyecto tambi\u00e9n tiene el objetivo de apoyar la colaboraci\u00f3n y el intercambio de informaci\u00f3n permanentes entre funcionarios de comercio y medio ambiente de los tres pa\u00edses, con miras a mejorar la coordinaci\u00f3n regional y nacional, lo que incluye la coordinaci\u00f3n entre la CCA y la CLC del TLCAN.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La evaluaci\u00f3n ambiental permanente del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales del TLCAN y se ampliar\u00e1 la comprensi\u00f3n de los v\u00ednculos entre medio ambiente y comercio para promover la coherencia de las pol\u00edticas, a escala tanto nacional como regional, en Am\u00e9rica del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-11745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-economias-sustentables","status-concluido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Evaluaci\u00f3n ambiental del TLCAN &#8211; Proyectos de la CCA<\/title>\n<meta name=\"description\" content=\"La evaluaci\u00f3n ambiental del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluaci\u00f3n ambiental del TLCAN\" \/>\n<meta property=\"og:description\" content=\"La evaluaci\u00f3n ambiental permanente del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-18T21:29:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T22:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cecmain_adm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CECweb\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/\"},\"author\":{\"name\":\"cecmain_adm\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/person\\\/cfaad09db438c516cb646ff4ea6f47bd\"},\"headline\":\"Evaluaci\u00f3n ambiental del TLCAN\",\"datePublished\":\"2010-10-18T21:29:59+00:00\",\"dateModified\":\"2025-06-16T22:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_nafta.jpg\",\"articleSection\":[\"Vida y Econom\u00edas Sustentables\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/\",\"name\":\"Evaluaci\u00f3n ambiental del TLCAN &#8211; Proyectos de la CCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_nafta.jpg\",\"datePublished\":\"2010-10-18T21:29:59+00:00\",\"dateModified\":\"2025-06-16T22:07:55+00:00\",\"description\":\"La evaluaci\u00f3n ambiental del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_nafta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ge_nafta.jpg\",\"width\":600,\"height\":342,\"caption\":\"CEC Projects - Extreme heat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/evaluacion-ambiental-del-tlcan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluaci\u00f3n ambiental del TLCAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/person\\\/cfaad09db438c516cb646ff4ea6f47bd\",\"name\":\"cecmain_adm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g\",\"caption\":\"cecmain_adm\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Evaluaci\u00f3n ambiental del TLCAN &#8211; Proyectos de la CCA","description":"La evaluaci\u00f3n ambiental del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/","og_locale":"es_ES","og_type":"article","og_title":"Evaluaci\u00f3n ambiental del TLCAN","og_description":"La evaluaci\u00f3n ambiental permanente del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales del","og_url":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_published_time":"2010-10-18T21:29:59+00:00","article_modified_time":"2025-06-16T22:07:55+00:00","og_image":[{"width":600,"height":342,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg","type":"image\/jpeg"}],"author":"cecmain_adm","twitter_card":"summary_large_image","twitter_creator":"@CECweb","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#article","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/"},"author":{"name":"cecmain_adm","@id":"https:\/\/www.cec.org\/es\/#\/schema\/person\/cfaad09db438c516cb646ff4ea6f47bd"},"headline":"Evaluaci\u00f3n ambiental del TLCAN","datePublished":"2010-10-18T21:29:59+00:00","dateModified":"2025-06-16T22:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/"},"wordCount":122,"publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"image":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg","articleSection":["Vida y Econom\u00edas Sustentables"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/","url":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/","name":"Evaluaci\u00f3n ambiental del TLCAN &#8211; Proyectos de la CCA","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg","datePublished":"2010-10-18T21:29:59+00:00","dateModified":"2025-06-16T22:07:55+00:00","description":"La evaluaci\u00f3n ambiental del TLCAN es una piedra angular en el trabajo de la CCA. En este proyecto se monitorear\u00e1n los efectos ambientales...","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/ge_nafta.jpg","width":600,"height":342,"caption":"CEC Projects - Extreme heat"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/evaluacion-ambiental-del-tlcan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Evaluaci\u00f3n ambiental del TLCAN"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"},{"@type":"Person","@id":"https:\/\/www.cec.org\/es\/#\/schema\/person\/cfaad09db438c516cb646ff4ea6f47bd","name":"cecmain_adm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8f608e33cee97f3c3c65bd1a9f0c7bf3e6726944b6bfc60ad0a39ccaf49f67a?s=96&d=mm&r=g","caption":"cecmain_adm"}}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/comments?post=11745"}],"version-history":[{"count":4,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11745\/revisions"}],"predecessor-version":[{"id":49444,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/posts\/11745\/revisions\/49444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/4609"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=11745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/categories?post=11745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/tags?post=11745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}