{"id":51214,"date":"2022-12-06T13:36:38","date_gmt":"2022-12-06T18:36:38","guid":{"rendered":"http:\/\/www.cec.org\/?page_id=51214"},"modified":"2024-07-11T13:33:22","modified_gmt":"2024-07-11T17:33:22","slug":"cop15","status":"publish","type":"page","link":"https:\/\/www.cec.org\/es\/cop15\/","title":{"rendered":"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)"},"content":{"rendered":"<p>\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica se celebrar\u00e1 del 7 al 19 de diciembre de 2022, y la CCA tiene la fortuna de que tan trascendente acontecimiento tenga lugar a apenas un par de manzanas de nuestras oficinas.<\/p>\n<p>En el marco de la COP15, habr\u00e1 m\u00faltiples oportunidades de participar en eventos con la CCA, conocer nuestro trabajo y charlar con expertos y miembros del Secretariado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica se celebrar\u00e1 del 7 al 19 de diciembre de 2022, y la CCA tiene la fortuna de que tan trascendente acontecimiento tenga lugar a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51223,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-cop27.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-51214","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)<\/title>\n<meta name=\"description\" content=\"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/cop15\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)\" \/>\n<meta property=\"og:description\" content=\"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/cop15\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T17:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/SP-COP15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/\",\"name\":\"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/SP-COP15.jpg\",\"datePublished\":\"2022-12-06T18:36:38+00:00\",\"dateModified\":\"2024-07-11T17:33:22+00:00\",\"description\":\"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/SP-COP15.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/SP-COP15.jpg\",\"width\":600,\"height\":342,\"caption\":\"Banner for cop15\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/cop15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"alternateName\":\"CEC - CCA -CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)","description":"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/cop15\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)","og_description":"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la","og_url":"https:\/\/www.cec.org\/es\/cop15\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-07-11T17:33:22+00:00","og_image":[{"width":600,"height":342,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/SP-COP15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/cop15\/","url":"https:\/\/www.cec.org\/es\/cop15\/","name":"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/cop15\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/cop15\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/SP-COP15.jpg","datePublished":"2022-12-06T18:36:38+00:00","dateModified":"2024-07-11T17:33:22+00:00","description":"\u00bfEs usted una de las casi 20 mil personas que asistir\u00e1n a la COP15? La 15a. reuni\u00f3n anual de la Conferencia de las Partes en el Convenio sobre la Diversidad Biol\u00f3gica","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/cop15\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/cop15\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/cop15\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/SP-COP15.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/SP-COP15.jpg","width":600,"height":342,"caption":"Banner for cop15"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/cop15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00famese a la CCA en la Conferencia de las Naciones Unidas sobre Diversidad Biol\u00f3gica (#COP15)"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","alternateName":"CEC - CCA -CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/pages\/51214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/comments?post=51214"}],"version-history":[{"count":4,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/pages\/51214\/revisions"}],"predecessor-version":[{"id":51244,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/pages\/51214\/revisions\/51244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/51223"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=51214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}