{"id":34770,"date":"2019-10-28T13:43:47","date_gmt":"2019-10-28T17:43:47","guid":{"rendered":"http:\/\/www.cec.org\/newsletter\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/"},"modified":"2025-11-19T16:51:23","modified_gmt":"2025-11-19T21:51:23","slug":"estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico","status":"publish","type":"news","link":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/","title":{"rendered":"Estrena la CCA el video corto \u00abVoces del corredor migratorio del Pac\u00edfico\u00bb"},"content":{"rendered":"<p><em>Nuevo documental \u2014disponible en\u00a0<\/em><a href=\"https:\/\/youtu.be\/Qb-2eGuXGmM\"><em>ingl\u00e9s<\/em><\/a><em>,\u00a0<\/em><a href=\"https:\/\/youtu.be\/yQkiSxXrgqw\"><em>espa\u00f1ol<\/em><\/a><em>\u00a0y\u00a0<\/em><a href=\"https:\/\/youtu.be\/4nU71_1dtlY\"><em>yup'ik central<\/em><\/a><em>\u2014 explora la conexi\u00f3n entre poblaciones humanas y aves migratorias a lo largo de la v\u00eda de migraci\u00f3n del Pac\u00edfico<\/em><\/p>\n<p><strong>Montreal, 28 de octubre de\u00a02019.<\/strong>\u00a0 La\u00a0<a href=\"http:\/\/www.cec.org\/es\">Comisi\u00f3n para la Cooperaci\u00f3n Ambiental<\/a>\u00a0(CCA) produjo, en asociaci\u00f3n con el Laboratorio de Ornitolog\u00eda de la Universidad de Cornell (<a href=\"https:\/\/www.birds.cornell.edu\/home\/\"><em>Cornell Lab of Ornithology<\/em><\/a>), un\u00a0breve documental titulado\u00a0<em>Voces del corredor migratorio del Pac\u00edfico\u00a0<\/em>(<a href=\"https:\/\/youtu.be\/yQkiSxXrgqw\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Voices of the Pacific Flyway<\/em><\/a>), cuyo lanzamiento tuvo lugar en el marco de la\u00a0<a href=\"https:\/\/audubonpanama.org\/index.php?option=com_content&view=article&id=80&catid=21\">octava reuni\u00f3n del Grupo de Aves Playeras del Hemisferio Occidental<\/a>. Este material audiovisual presenta las voces de tres comunidades asentadas a lo largo de la v\u00eda migratoria del Pac\u00edfico, ligadas por una apreciaci\u00f3n compartida de las aves playeras.<\/p>\n<p class=\"rtecenter\"><iframe loading=\"lazy\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/yQkiSxXrgqw\" width=\"560\"><\/iframe><\/p>\n<p>Estas sorprendentes aves emprenden migraciones marat\u00f3nicas: cada a\u00f1o recorren miles de kil\u00f3metros a lo largo de la l\u00ednea costera y, en su traves\u00eda,\u00a0van haciendo\u00a0escala en m\u00faltiples sitios clave. Tan espectaculares migraciones generan conexiones entre lugares remotos y dis\u00edmiles, y tambi\u00e9n vinculan a una gran diversidad de personas.<\/p>\n<p>As\u00ed, las aves playeras nos conectan: desde las costas de la pen\u00ednsula de Baja California, en M\u00e9xico (donde una comunidad celebra la llegada y el paso de las aves playeras), hasta la bah\u00eda Hooper, en el delta Yuk\u00f3n-Kuskokwim, en Alaska (donde durante miles de a\u00f1os las aves han constituido una importante fuente de alimentos y recursos culturales),\u00a0pasando por el\u00a0 estuario Grays Harbor, en el estado de Washington, Estados Unidos (donde un equipo internacional de investigadores trabaja con el fin de descifrar los misterios de las rutas de estas especies de avifauna).<\/p>\n<p>Producci\u00f3n del Laboratorio de Ornitolog\u00eda de la Universidad de Cornell, el documental se realiz\u00f3 como parte de una\u00a0<a href=\"https:\/\/www.cec.org\/es\/nuestro-trabajo\/proyectos\/conservaci%C3%B3n-de-las-aves-playeras-por-medio-de-la-participaci%C3%B3n-comunitaria\">iniciativa de la CCA<\/a>\u00a0\u2014en cumplimiento del mandato de conservar, proteger y mejorar el medio ambiente compartido de Am\u00e9rica del Norte\u2014 orientada a procurar la participaci\u00f3n en actividades de conservaci\u00f3n de comunidades establecidas a lo largo de los corredores migratorios de aves playeras, y cont\u00f3 con la supervisi\u00f3n y direcci\u00f3n de la CCA y sus socios, incluidos el Servicio de Pesca y Vida Silvestre (<em>Fish and Wildlife Service<\/em>, USFWS) de Estados Unidos, el Servicio Forestal de Estados Unidos (<em>United States Forest Service<\/em>, USFS), la Divisi\u00f3n de Subsistencia del Departamento de Pesca y Caza de Alaska (<em>Alaska Department of Fish and Game<\/em>), el Departamento de Pesca y Vida Silvestre del estado de Washington (<em>Washington State Department of Fish and Wildlife<\/em>) y la Comisi\u00f3n Nacional para el Conocimiento y Uso de la Biodiversidad (Conabio) de M\u00e9xico, adem\u00e1s del apoyo de diversos colaboradores locales y regionales.<\/p>\n<p><a href=\"https:\/\/youtu.be\/yQkiSxXrgqw\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Voces del corredor migratorio del Pac\u00edfico<\/em><\/a>\u00a0se dirige, sobre todo, a grupos comprometidos en actividades educativas o en favor de la conservaci\u00f3n a lo largo de la v\u00eda migratoria del Pac\u00edfico, y se encuentra disponible \u2014sin costo alguno\u2014 en\u00a0<a href=\"https:\/\/youtu.be\/Qb-2eGuXGmM\">ingl\u00e9s<\/a>,\u00a0<a href=\"https:\/\/youtu.be\/yQkiSxXrgqw\">espa\u00f1ol<\/a>\u00a0y\u00a0<a href=\"https:\/\/youtu.be\/4nU71_1dtlY\">yup'ik central<\/a>.<\/p>\n<p><strong>Acerca del<\/strong>\u00a0<strong>Laboratorio de Ornitolog\u00eda de la Universidad de Cornell<\/strong><br \/>\nEl Laboratorio de Ornitolog\u00eda de la Universidad de Cornell (<a href=\"https:\/\/www.birds.cornell.edu\/\"><em>Cornell Lab of Ornithology<\/em><\/a>), organizaci\u00f3n sin fines de lucro que se mantiene gracias al apoyo de sus miembros, se dedica a la interpretaci\u00f3n y conservaci\u00f3n de la diversidad biol\u00f3gica mediante actividades de investigaci\u00f3n, educaci\u00f3n y ciencia ciudadana con un enfoque centrado en las aves.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo documental \u2014disponible en\u00a0ingl\u00e9s,\u00a0espa\u00f1ol\u00a0y\u00a0yup&#8217;ik central\u2014 explora la conexi\u00f3n entre poblaciones humanas y aves migratorias a lo largo de la v\u00eda de migraci\u00f3n del Pac\u00edfico Montreal, 28 de octubre de\u00a02019.\u00a0 La\u00a0Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\u00a0(CCA) produjo, en asociaci\u00f3n con el Laboratorio de Ornitolog\u00eda de la Universidad de Cornell (Cornell Lab of Ornithology), un\u00a0breve documental titulado\u00a0Voces del [&hellip;]<\/p>\n","protected":false},"featured_media":6616,"template":"","class_list":["post-34770","news","type-news","status-publish","has-post-thumbnail","hentry","feed-alianzas-externas","feed-ecosistemas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CEC premieres short film &quot;Voices of the Pacific Flyway&quot;<\/title>\n<meta name=\"description\" content=\"Short documentary entitled\u00a0Voices of the Pacific Flyway. The documentary, launched at the\u00a08th\u00a0Western Hemisphere Shorebird Group Meeting...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrena la CCA el video corto &quot;Voces del corredor migratorio del Pac\u00edfico&quot;\" \/>\n<meta property=\"og:description\" content=\"Nuevo documental \u2014disponible en\u00a0ingl\u00e9s,\u00a0espa\u00f1ol\u00a0y\u00a0yup&#039;ik central\u2014 explora la conexi\u00f3n entre poblaciones humanas y aves migratorias a lo largo de la v\u00eda de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T21:51:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/nashorebirds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/\",\"name\":\"CEC premieres short film \\\"Voices of the Pacific Flyway\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nashorebirds.jpg\",\"datePublished\":\"2019-10-28T17:43:47+00:00\",\"dateModified\":\"2025-11-19T21:51:23+00:00\",\"description\":\"Short documentary entitled\u00a0Voices of the Pacific Flyway. The documentary, launched at the\u00a08th\u00a0Western Hemisphere Shorebird Group Meeting...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nashorebirds.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nashorebirds.jpg\",\"width\":600,\"height\":400,\"caption\":\"Voices of the Pacific Flyway\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estrena la CCA el video corto \u00abVoces del corredor migratorio del Pac\u00edfico\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CEC premieres short film \"Voices of the Pacific Flyway\"","description":"Short documentary entitled\u00a0Voices of the Pacific Flyway. The documentary, launched at the\u00a08th\u00a0Western Hemisphere Shorebird Group Meeting...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/","og_locale":"es_ES","og_type":"article","og_title":"Estrena la CCA el video corto \"Voces del corredor migratorio del Pac\u00edfico\"","og_description":"Nuevo documental \u2014disponible en\u00a0ingl\u00e9s,\u00a0espa\u00f1ol\u00a0y\u00a0yup'ik central\u2014 explora la conexi\u00f3n entre poblaciones humanas y aves migratorias a lo largo de la v\u00eda de","og_url":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2025-11-19T21:51:23+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/nashorebirds.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/","url":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/","name":"CEC premieres short film \"Voices of the Pacific Flyway\"","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/nashorebirds.jpg","datePublished":"2019-10-28T17:43:47+00:00","dateModified":"2025-11-19T21:51:23+00:00","description":"Short documentary entitled\u00a0Voices of the Pacific Flyway. The documentary, launched at the\u00a08th\u00a0Western Hemisphere Shorebird Group Meeting...","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/nashorebirds.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/10\/nashorebirds.jpg","width":600,"height":400,"caption":"Voices of the Pacific Flyway"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/novedades\/estrena-la-cca-el-video-corto-voces-del-corredor-migratorio-del-pacifico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades","item":"https:\/\/www.cec.org\/es\/novedades\/"},{"@type":"ListItem","position":3,"name":"Estrena la CCA el video corto \u00abVoces del corredor migratorio del Pac\u00edfico\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/news\/34770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/6616"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=34770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}