{"id":30116,"date":"2012-12-10T00:00:00","date_gmt":"2012-12-10T05:00:00","guid":{"rendered":"http:\/\/www.cec.org\/news\/media-releases\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/"},"modified":"2026-01-24T13:52:37","modified_gmt":"2026-01-24T18:52:37","slug":"comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca","status":"publish","type":"news","link":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/","title":{"rendered":"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA"},"content":{"rendered":"<p><em>En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y regional.<\/em><\/p>\n<p><strong>Montreal, a\u00a010 de\u00a0diciembre de 2012.\u00a0<\/strong>Si ahora mismo una empresa o autoridad ambiental quisiera estimar el impacto de las diferentes medidas de reducci\u00f3n de los gases de efecto invernadero (GEI) y compararlo entre los tres pa\u00edses o distintas zonas de Am\u00e9rica del Norte, se enfrentar\u00eda al hecho de que en la regi\u00f3n existen m\u00faltiples marcos para el registro de emisiones de GEI, con niveles de detalle y complejidad divergentes.<\/p>\n<p>En respuesta a esta situaci\u00f3n, Canad\u00e1, Estados Unidos y M\u00e9xico est\u00e1n buscando la forma de mejorar la comparabilidad de los datos sobre emisiones en Am\u00e9rica del Norte a fin de contribuir a la consecuci\u00f3n de objetivos y el mejoramiento de normas, reglamentos y pol\u00edticas sobre emisiones de carbono en el \u00e1mbito nacional para 2015, esto como parte de las prioridades estrat\u00e9gicas que estableci\u00f3 el Consejo de la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA).<\/p>\n<p>Las iniciativas conjuntas encaminadas a establecer una pol\u00edtica trinacional que favorezca la reducci\u00f3n de las emisiones de GEI en Am\u00e9rica del Norte depender\u00e1n en \u00faltima instancia de que se cuente con datos e informaci\u00f3n comparables sobre tales emisiones en cada uno de los pa\u00edses.<\/p>\n<p>Gracias al trabajo conjunto realizado por medio de la CCA, los pa\u00edses ya han dado un importante primer paso para considerar el estado de comparabilidad de los datos sobre emisiones a escalas nacional y subnacional al concluir el informe de antecedentes<em>Evaluaci\u00f3n de la comparabilidad de los inventarios de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte<\/em>.<\/p>\n<p>Este informe documenta c\u00f3mo, en la actualidad, Am\u00e9rica del Norte cuenta con m\u00faltiples mecanismos \u2014voluntarios y obligatorios, de alcance nacional y subnacional, y con distintos grados de detalle y complejidad\u2014 para informar sobre las emisiones de GEI. Los correspondientes requisitos de registro de las emisiones de gases de efecto invernadero para establecimientos y sectores industriales var\u00edan entre los tres pa\u00edses de acuerdo con la jurisdicci\u00f3n. El informe tambi\u00e9n aborda las emisiones de carbono negro, agente clim\u00e1tico de vida corta conformado por finas part\u00edculas de aerosol transportadas por el aire, que duran poco en la atm\u00f3sfera pero que representan potentes fuentes del cambio clim\u00e1tico inducido por el ser humano. Los procesos de combusti\u00f3n son una de las principales fuentes de carbono negro.<\/p>\n<p>En las pr\u00f3ximas semanas, un grupo t\u00e9cnico integrado por representantes de los tres pa\u00edses se reunir\u00e1 y aprovechar\u00e1 los resultados de este informe de la CCA para formular recomendaciones a los ministros de medio ambiente de los tres pa\u00edses de Am\u00e9rica del Norte.<\/p>\n<p>Entre los datos y cifras que el informe presenta, destacan los siguientes:<\/p>\n<ul>\n<li>Cuando menos cinco provincias y territorios canadienses, 31 entidades federativas de Estados Unidos y 10 estados de M\u00e9xico han concluido inventarios de emisiones de gases de efecto invernadero, independientemente de los respectivos inventarios nacionales (p\u00e1gina 22).<\/li>\n<li>El sector energ\u00e9tico representa la categor\u00eda de fuentes con mayores emisiones de GEI en cada uno de los pa\u00edses (p\u00e1gina iv).<\/li>\n<li>Con el prop\u00f3sito de generar un inventario de emisiones de carbono negro (CN), la Agencia de Protecci\u00f3n Ambiental (<em>Environmental Protection Agency<\/em>, EPA) de Estados Unidos ha elaborado un marco que incluye factores de emisi\u00f3n para fuentes espec\u00edficas. Algunos de estos factores est\u00e1n siendo ya utilizados por los gobiernos canadiense y mexicano. La quema de combustibles f\u00f3siles, las estufas de le\u00f1a, los incendios forestales y las quemas prescritas figuran entre las fuentes de carbono negro (v\u00e9ase el cuadro 3, p\u00e1ginas 9-10).<\/li>\n<li>Canad\u00e1 y Estados Unidos tienen una cobertura m\u00e1s detallada que M\u00e9xico, dado el estatus que \u00e9ste guarda como pa\u00eds no incluido en el anexo\u00a0I, de acuerdo con las directrices establecidas en la Convenci\u00f3n Marco de las Naciones Unidas sobre el Cambio Clim\u00e1tico (CMNUCC) (p\u00e1gina 3).<\/li>\n<li>Se identificaron numerosas diferencias en sectores y fuentes de emisi\u00f3n espec\u00edficos entre los inventarios de GEI de Canad\u00e1, Estados Unidos y M\u00e9xico. Por ejemplo, las emisiones generadas a partir de la incineraci\u00f3n de desechos se registran en Estados Unidos como parte del sector energ\u00e9tico, mientras que en Canad\u00e1 y M\u00e9xico pertenecen al sector de desechos (p\u00e1gina 16).<\/li>\n<\/ul>\n<p>Si desea informaci\u00f3n m\u00e1s detallada sobre la labor que realiza la CCA en materia de cambio clim\u00e1tico y a favor de econom\u00edas bajas en carbono, visite:\u00a0www.cec.org\/GEI.<\/p>\n<p>Mant\u00e9ngase al d\u00eda respecto del trabajo de la CCA y s\u00edganos en Twitter, en:\u00a0<a href=\"http:\/\/twitter.com\/CECweb\">@CECweb<\/a>, o v\u00eda Facebook, en:\u00a0<a href=\"http:\/\/www.facebook.org\/CCAconecta\">www.facebook.org\/CCAconecta<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y regional. Montreal, a\u00a010 de\u00a0diciembre de 2012.\u00a0Si ahora mismo una empresa o autoridad ambiental quisiera estimar el impacto de las diferentes medidas de reducci\u00f3n de los gases de efecto invernadero (GEI) y [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-30116","news","type-news","status-publish","hentry","feed-consejo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA<\/title>\n<meta name=\"description\" content=\"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA\" \/>\n<meta property=\"og:description\" content=\"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-24T18:52:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\\\/\",\"name\":\"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"datePublished\":\"2012-12-10T05:00:00+00:00\",\"dateModified\":\"2026-01-24T18:52:37+00:00\",\"description\":\"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/novedades\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"alternateName\":\"CEC - CCA -CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA","description":"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/","og_locale":"es_ES","og_type":"article","og_title":"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA","og_description":"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y","og_url":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2026-01-24T18:52:37+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/cec-cover2023.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/","url":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/","name":"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"datePublished":"2012-12-10T05:00:00+00:00","dateModified":"2026-01-24T18:52:37+00:00","description":"En materia de emisiones, llenar los vac\u00edos y mejorar la comparabilidad de los datos son elementos clave para alcanzar objetivos a escalas nacional y","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/novedades\/comparacion-de-emisiones-de-gases-de-efecto-invernadero-y-carbono-negro-en-america-del-norte-nuevo-informe-de-la-cca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Novedades","item":"https:\/\/www.cec.org\/es\/novedades\/"},{"@type":"ListItem","position":3,"name":"Comparaci\u00f3n de emisiones de gases de efecto invernadero y carbono negro en Am\u00e9rica del Norte: nuevo informe de la CCA"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","alternateName":"CEC - CCA -CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/news\/30116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=30116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}