{"id":46396,"date":"2021-10-25T16:58:54","date_gmt":"2021-10-25T20:58:54","guid":{"rendered":"http:\/\/www.cec.org\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/"},"modified":"2024-06-22T12:27:41","modified_gmt":"2024-06-22T16:27:41","slug":"mikmaw-wildfire-resilience-initiative","status":"publish","type":"grants","link":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/","title":{"rendered":"Iniciativa para fortalecer la resiliencia en las comunidades mi&#8217;kmaw en caso de incendios forestales naturales"},"content":{"rendered":"<h4><strong>Antecedentes<\/strong><\/h4>\n<p>El cambio clim\u00e1tico es un fen\u00f3meno que afecta numerosos aspectos de nuestras comunidades al provocar aumentos en las temperaturas, cambios en los patrones meteorol\u00f3gicos, alteraciones o perturbaciones en la migraci\u00f3n de especies y un aumento en la incidencia de eventos clim\u00e1ticos y meteorol\u00f3gicos extremos, entre otros efectos. En los \u00faltimos a\u00f1os se ha observado un notorio incremento en la incidencia de incendios forestales en la regi\u00f3n occidental de Canad\u00e1, lo que ha dado lugar a una importante preocupaci\u00f3n para las comunidades mi\u2019kmaw en las provincias canadienses del Atl\u00e1ntico, quienes temen que pronto comenzar\u00e1n a atestiguar aumentos similares en los incendios forestales en entornos naturales y construidos de su zona geogr\u00e1fica. En ese sentido, en 2018 se llevaron a cabo estudios en materia de incendios forestales en siete comunidades mi\u2019kmaw en Nueva Escocia. Con base en los resultados de las evaluaciones efectuadas, todas las comunidades participantes se clasificaron en las categor\u00edas de riesgo moderado a extremo de ocurrencia de incendios forestales, y la mayor\u00eda se consider\u00f3 en riesgo alto a extremo. Estas comunidades recibieron recomendaciones a efecto de prepararse y mitigar el riesgo de incendios forestales; adem\u00e1s, 40 de sus integrantes participaron en sesiones de capacitaci\u00f3n como bomberos para combatir incendios en tierras silvestres. Con todo, a\u00fan se requieren acciones adicionales y mayores recursos para atender las inquietudes de las comunidades al respecto y aumentar su resiliencia frente a incendios forestales.<\/p>\n<h4><strong>Metas<\/strong><\/h4>\n<p>El principal desaf\u00edo de este proyecto estriba en dar el siguiente paso y, aprovechando su componente de capacitaci\u00f3n y evaluaci\u00f3n, aunado al apoyo comunitario, poner en acci\u00f3n estrategias de mitigaci\u00f3n de los incendios forestales. Para ello, se elegir\u00e1 una comunidad piloto en funci\u00f3n de su riesgo \u2014alto o elevado\u2014 de sufrir incendios forestales, as\u00ed como de su tama\u00f1o, ubicaci\u00f3n geogr\u00e1fica y respaldo comunitario manifestado en relaci\u00f3n con la iniciativa. El objetivo general del proyecto consiste en promover acciones en curso encaminadas a mitigar los incendios forestales; crear un marco de apoyo para las comunidades, y lograr el respaldo rec\u00edproco entre \u00e9stas.<\/p>\n<h4><strong>Actividades principales<\/strong><\/h4>\n<ul>\n<li>Examinar las evaluaciones en materia de incendios forestales realizadas en las comunidades participantes, as\u00ed como aspectos demogr\u00e1ficos y otros relacionados con la preparaci\u00f3n y el apoyo expresado hacia el proyecto. Llevar a cabo reuniones con miembros de cada una de estas comunidades y los socios de la iniciativa, a fin de analizar oportunidades para la realizaci\u00f3n del estudio piloto.<\/li>\n<li>Organizar un taller comunitario de capacitaci\u00f3n en torno a pr\u00e1cticas de la iniciativa FireSmart, dividido en dos segmentos: una sesi\u00f3n en aula y otra de pr\u00e1ctica en campo. Celebrar uno o varios eventos en el marco de un d\u00eda dedicado a la mitigaci\u00f3n de incendios forestales en la comunidad piloto.<\/li>\n<li>Mitigar el riesgo de incendios forestales al interior de la comunidad piloto mediante el establecimiento de zonas prioritarias para dicha comunidad, al igual que \u00e1reas destinadas a un manejo preventivo de incendios forestales, con tareas de desmonte, remoci\u00f3n de desechos y limpieza en las inmediaciones de edificaciones en la comunidad.<\/li>\n<li>Planificar e implementar trabajos en curso y nuevos de manejo de \u00e1reas verdes y del entorno conforme a los criterios FireSmart. Evaluar las fuentes de agua de la comunidad piloto y determinar si se requiere instalar un sistema de almacenamiento de agua contra incendios, as\u00ed como el costo que dicha obra supondr\u00eda de ser necesaria.<\/li>\n<\/ul>\n<h4><strong>Resultados\u00a0<\/strong><\/h4>\n<p>Aunque la intervenci\u00f3n se llevar\u00e1 a cabo \u00fanicamente en una comunidad piloto, se derivar\u00e1n m\u00e9todos de bajo costo que se compartir\u00e1n para su implementaci\u00f3n en otros lugares, con miras a asegurar la participaci\u00f3n de todas las comunidades. Las acciones emprendidas por la comunidad piloto se dar\u00e1n a conocer tanto a las dem\u00e1s comunidades como al Comit\u00e9 Consultivo de Acciones Contra el Cambio Clim\u00e1tico (<em>Climate Action Advisory Committee<\/em>), organismo encargado de prestar orientaci\u00f3n sobre proyectos relacionados con medidas de adaptaci\u00f3n al cambio clim\u00e1tico y preparaci\u00f3n en casos de emergencia en comunidades ind\u00edgenas asentadas en territorio continental de Nueva Escocia. Encontrar soluciones y aumentar la capacidad de las comunidades por medio de recursos, financiamiento y una participaci\u00f3n comunitaria sistem\u00e1tica, y tambi\u00e9n mediante el establecimiento de una red de apoyo, redundar\u00e1 en una mayor preparaci\u00f3n de estas poblaciones para hacer frente a los incendios forestales, as\u00ed como en una mejor preparaci\u00f3n en t\u00e9rminos generales al modelizar esta estrategia para hacer frente a otras situaciones de emergencia y eventos clim\u00e1tico-meteorol\u00f3gicos extremos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antecedentes El cambio clim\u00e1tico es un fen\u00f3meno que afecta numerosos aspectos de nuestras comunidades al provocar aumentos en las temperaturas, cambios en los patrones meteorol\u00f3gicos, alteraciones o perturbaciones en la migraci\u00f3n de especies y un aumento en la incidencia de eventos clim\u00e1ticos y meteorol\u00f3gicos extremos, entre otros efectos. En los \u00faltimos a\u00f1os se ha observado [&hellip;]<\/p>\n","protected":false},"featured_media":46365,"template":"","class_list":["post-46396","grants","type-grants","status-publish","has-post-thumbnail","hentry","country-canada-es","status-concluido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Iniciativa para fortalecer la resiliencia en las comunidades mi&#039;kmaw en caso de incendios forestales naturales<\/title>\n<meta name=\"description\" content=\"Una importante preocupaci\u00f3n para las comunidades mi\u2019kmaw en las provincias canadienses del Atl\u00e1ntico...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iniciativa para fortalecer la resiliencia en las comunidades mi&#039;kmaw en caso de incendios forestales naturales\" \/>\n<meta property=\"og:description\" content=\"Antecedentes El cambio clim\u00e1tico es un fen\u00f3meno que afecta numerosos aspectos de nuestras comunidades al provocar aumentos en las temperaturas, cambios en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T16:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/project-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/\",\"name\":\"Iniciativa para fortalecer la resiliencia en las comunidades mi'kmaw en caso de incendios forestales naturales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/project-01.jpg\",\"datePublished\":\"2021-10-25T20:58:54+00:00\",\"dateModified\":\"2024-06-22T16:27:41+00:00\",\"description\":\"Una importante preocupaci\u00f3n para las comunidades mi\u2019kmaw en las provincias canadienses del Atl\u00e1ntico...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/project-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/project-01.jpg\",\"width\":510,\"height\":340,\"caption\":\"The Confederacy of Mainland Mi'kmaq\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/mikmaw-wildfire-resilience-initiative\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iniciativa para fortalecer la resiliencia en las comunidades mi&#8217;kmaw en caso de incendios forestales naturales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Iniciativa para fortalecer la resiliencia en las comunidades mi'kmaw en caso de incendios forestales naturales","description":"Una importante preocupaci\u00f3n para las comunidades mi\u2019kmaw en las provincias canadienses del Atl\u00e1ntico...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/","og_locale":"es_ES","og_type":"article","og_title":"Iniciativa para fortalecer la resiliencia en las comunidades mi'kmaw en caso de incendios forestales naturales","og_description":"Antecedentes El cambio clim\u00e1tico es un fen\u00f3meno que afecta numerosos aspectos de nuestras comunidades al provocar aumentos en las temperaturas, cambios en","og_url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-06-22T16:27:41+00:00","og_image":[{"width":510,"height":340,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/project-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/","url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/","name":"Iniciativa para fortalecer la resiliencia en las comunidades mi'kmaw en caso de incendios forestales naturales","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/project-01.jpg","datePublished":"2021-10-25T20:58:54+00:00","dateModified":"2024-06-22T16:27:41+00:00","description":"Una importante preocupaci\u00f3n para las comunidades mi\u2019kmaw en las provincias canadienses del Atl\u00e1ntico...","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/project-01.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/project-01.jpg","width":510,"height":340,"caption":"The Confederacy of Mainland Mi'kmaq"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/mikmaw-wildfire-resilience-initiative\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Iniciativa para fortalecer la resiliencia en las comunidades mi&#8217;kmaw en caso de incendios forestales naturales"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants\/46396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/grants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/46365"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=46396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}