{"id":11252,"date":"2015-12-02T18:24:59","date_gmt":"2015-12-02T23:24:59","guid":{"rendered":"http:\/\/www.cec.org\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/"},"modified":"2024-06-22T12:28:02","modified_gmt":"2024-06-22T16:28:02","slug":"proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria","status":"publish","type":"grants","link":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/","title":{"rendered":"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria"},"content":{"rendered":"<h4>Antecedentes<\/h4>\n<p>Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n corresponde a insectos: mariposas, polillas, moscas, escarabajos, avispas y abejas. Estos insectos son responsables de la polinizaci\u00f3n de tres cuartas partes de todas las plantas con flores del mundo, entre las que se incluye gran parte de la vegetaci\u00f3n y los cultivos que sirven para alimento humano. Sin embargo, dado el descenso observado en las poblaciones de polinizadores en Am\u00e9rica del Norte, las plantas alimenticias y productoras de alimentos tienden a polinizarse menos. Las especies polinizadoras, como las abejas solitarias, son pues indispensables para la polinizaci\u00f3n de la vegetaci\u00f3n de aprovechamiento para el ser humano, como huertos, jardines florales y cultivos agr\u00edcolas.<\/p>\n<h4>Metas<\/h4>\n<ol>\n<li>Crear mayor conciencia sobre la importancia de las especies polinizadoras, la problem\u00e1tica de la disminuci\u00f3n en sus poblaciones y las medidas y soluciones necesarias para su conservaci\u00f3n. Esta sensibilizaci\u00f3n se realizar\u00e1 por medio de p\u00e1ginas web especializadas y folletos, as\u00ed como tambi\u00e9n v\u00eda medios de comunicaci\u00f3n reconocidos, comunitarios y sociales.<\/li>\n<li>Aumentar los sitios de anidamiento de abejas y otras especies polinizadoras solitarias mediante la construcci\u00f3n e instalaci\u00f3n de \u201choteles\u201d u \u201chospederos\u201d para abejas, y animar a grupos comunitarios, empresas y ciudadanos en general a actuar en consonancia.<\/li>\n<li>Expandir el h\u00e1bitat de especies polinizadoras con la creaci\u00f3n de un jard\u00edn de flores nativas en el primer hotel para abejas instalado en la sede de la Fundaci\u00f3n Comunitaria de Edmonton (<em>Edmonton Community Foundation<\/em>), y distribuir paquetes de semillas de especies nativas entre la ciudadan\u00eda para que las siembre en sus jardines.<\/li>\n<\/ol>\n<h4>Actividades principales<\/h4>\n<ol>\n<li>Organizar, en bibliotecas, ligas comunitarias y locales comerciales, talleres sobre c\u00f3mo construir hoteles para abejas, a fin de que residentes de la localidad aprendan a construir un hospedero propio en su jard\u00edn.<\/li>\n<li>Recurrir a voluntarios que ayuden a construir hospederos para abejas y colocarlos en establecimientos, iglesias y escuelas de la localidad, as\u00ed como en las instalaciones del fideicomiso Edmonton and Area Land Trust (EALT), con miras a fomentar la conservaci\u00f3n de las especies polinizadoras.<\/li>\n<li>Construir un hospedero para abejas de grandes dimensiones y muy visible en el Santuario Larch, \u00e1rea natural ubicada al interior de la ciudad de Edmonton, donde EALT y las autoridades municipales trabajan conjuntamente en una servidumbre ecol\u00f3gica de conservaci\u00f3n, otorgada a EALT con fines educativos y de resguardo ambiental.<\/li>\n<li>Colaborar con el Grupo en Favor de la Flora Nativa de Edmonton (<em>Edmonton Native Plant Group<\/em>) en la instalaci\u00f3n de un jard\u00edn de flores nativas en el sitio del primer hotel para abejas, en la sede de la Fundaci\u00f3n Comunitaria de Edmonton, y distribuir entre la ciudadan\u00eda semillas de flores nativas para incentivar su siembra.<\/li>\n<li>Reestructurar el sitio web de la organizaci\u00f3n a fin de integrar el tema de la protecci\u00f3n de especies polinizadoras y lo relativo a este proyecto, para lo cual se incorporar\u00e1n m\u00e1s informaci\u00f3n y recursos de b\u00fasqueda f\u00e1cil, adem\u00e1s de incluirse una galer\u00eda con ejemplos. Asimismo, elaborar folletos, carteles y un anuncio para crear mayor conciencia a escala local y disponer de m\u00e1s materiales sobre c\u00f3mo proteger a las especies polinizadoras.<\/li>\n<\/ol>\n<h4>Resultados<\/h4>\n<p>Este proyecto permitir\u00e1 aumentar el h\u00e1bitat urbano adecuado para especies polinizadoras en Edmonton y sus alrededores. Al tener una mayor conciencia sobre el crucial papel que estas especies desempe\u00f1an, la ciudadan\u00eda sabr\u00e1 mejor c\u00f3mo contribuir a su protecci\u00f3n, lo que incluye aprender a construir hospederos para abejas. Se dispondr\u00e1 de una mayor cantidad de \u201choteles para abejas\u201d gracias a su instalaci\u00f3n directa en establecimientos, iglesias y escuelas locales; a la participaci\u00f3n ciudadana en su construcci\u00f3n, en talleres organizados por EALT, y a la difusi\u00f3n entre la poblaci\u00f3n en general de instrucciones sobre c\u00f3mo dise\u00f1ar, construir e instalar hospederos propios. Todas estas tareas generar\u00e1n una mayor sensibilizaci\u00f3n entre los ciudadanos en torno a la importancia de las especies polinizadoras y la conservaci\u00f3n de su h\u00e1bitat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n corresponde a insectos: mariposas, polillas, moscas, escarabajos, avispas y abejas. Estos insectos son responsables de la polinizaci\u00f3n de tres cuartas partes de todas las plantas con flores del mundo, entre las que se [&hellip;]<\/p>\n","protected":false},"featured_media":2990,"template":"","class_list":["post-11252","grants","type-grants","status-publish","has-post-thumbnail","hentry","country-canada-es","status-concluido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria<\/title>\n<meta name=\"description\" content=\"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria\" \/>\n<meta property=\"og:description\" content=\"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T16:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/pr1-protecting-polinators.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/\",\"name\":\"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pr1-protecting-polinators.jpg\",\"datePublished\":\"2015-12-02T23:24:59+00:00\",\"dateModified\":\"2024-06-22T16:28:02+00:00\",\"description\":\"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pr1-protecting-polinators.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pr1-protecting-polinators.jpg\",\"width\":600,\"height\":408,\"caption\":\"Bee Hotels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria","description":"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/","og_locale":"es_ES","og_type":"article","og_title":"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria","og_description":"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n","og_url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-06-22T16:28:02+00:00","og_image":[{"width":600,"height":408,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/pr1-protecting-polinators.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/","url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/","name":"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/pr1-protecting-polinators.jpg","datePublished":"2015-12-02T23:24:59+00:00","dateModified":"2024-06-22T16:28:02+00:00","description":"Antecedentes Si bien los murci\u00e9lagos y las aves figuran entre las especies polinizadoras, la mayor\u00eda de los organismos que cumplen esta funci\u00f3n","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/pr1-protecting-polinators.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/pr1-protecting-polinators.jpg","width":600,"height":408,"caption":"Bee Hotels"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/proteccion-de-especies-polinizadoras-mediante-la-colaboracion-comunitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n de especies polinizadoras mediante la colaboraci\u00f3n comunitaria"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants\/11252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/grants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/2990"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=11252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}