{"id":11237,"date":"2013-12-02T18:24:57","date_gmt":"2013-12-02T23:24:57","guid":{"rendered":"http:\/\/www.cec.org\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/"},"modified":"2024-06-22T12:28:13","modified_gmt":"2024-06-22T16:28:13","slug":"perspectivas-indigenas-respecto-al-lago-winnipeg","status":"publish","type":"grants","link":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/","title":{"rendered":"Perspectivas ind\u00edgenas respecto al lago Winnipeg"},"content":{"rendered":"<h4>ANTECEDENTES<\/h4>\n<p>El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades ind\u00edgenas. Debido a la carga excesiva de f\u00f3sforo generada por la actividad humana en esta vasta cuenca transfronteriza, el lago Winnipeg es uno de los lagos grandes m\u00e1s eutr\u00f3ficos del mundo. En 2013, el Global Nature Fund lo design\u00f3 \u201cLago amenazado del a\u00f1o\u201d. En t\u00e9rminos econ\u00f3micos, el deterioro de la salud de este lago pone en peligro las industrias pesquera y tur\u00edstica, adem\u00e1s de abatir el valor de la propiedad. En el \u00e1mbito ambiental, la eutrofizaci\u00f3n ha afectado la resiliencia de la cadena alimentaria del lago y podr\u00eda tener efectos nocivos de gran alcance en la biodiversidad. Por lo que toca al aspecto social, las floraciones de algas azul-verdosas t\u00f3xicas limitan el acceso al agua para la realizaci\u00f3n de actividades culturales y tradicionales, merman la potabilidad del agua y podr\u00edan afectar significativamente la salud ambiental de las comunidades pesqueras locales si las toxinas se acumulan en los peces.<\/p>\n<h4>METAS<\/h4>\n<p>Fomentar la inclusi\u00f3n de perspectivas ind\u00edgenas en la formulaci\u00f3n de soluciones en torno al lago Winnipeg.<\/p>\n<h4>ACTIVIDADES PRINCIPALES<\/h4>\n<p><em>Fomento y apoyo<\/em>: Fomentar la participaci\u00f3n y el desarrollo de capacidades entre las comunidades ind\u00edgenas del lago Winnipeg y apuntalar las incipientes prioridades en materia de monitoreo y pol\u00edtica.<\/p>\n<h4>RESULTADOS<\/h4>\n<p>Este proyecto permitir\u00e1 la inclusi\u00f3n de las perspectivas singulares, aunque a menudo marginalizadas, de los pueblos ind\u00edgenas, para fundamentar los enfoques de protecci\u00f3n y resguardo de las organizaciones aliadas. Se crear\u00e1n, asimismo, oportunidades para alentar una iniciativa consensuada de las comunidades ind\u00edgenas encaminada a proteger el lago Winnipeg. Si bien los resultados esperados a\u00fan no se determinan, pueden incluir, entre otros: una red de monitoreo de pueblos ind\u00edgenas; un proceso para documentar el conocimiento aut\u00f3ctono del lago; la creaci\u00f3n de indicadores de la salud del lago, seg\u00fan lo definido por las comunidades ind\u00edgenas, y la integraci\u00f3n de un \u00f3rgano consultivo ind\u00edgena para nutrir una pol\u00edtica significativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades ind\u00edgenas. Debido a la carga excesiva de f\u00f3sforo generada por la actividad humana en esta vasta cuenca transfronteriza, el lago Winnipeg es uno de los lagos grandes m\u00e1s eutr\u00f3ficos del [&hellip;]<\/p>\n","protected":false},"featured_media":2948,"template":"","class_list":["post-11237","grants","type-grants","status-publish","has-post-thumbnail","hentry","country-canada-es","status-concluido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perspectivas ind\u00edgenas respecto al lago Winnipeg<\/title>\n<meta name=\"description\" content=\"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perspectivas ind\u00edgenas respecto al lago Winnipeg\" \/>\n<meta property=\"og:description\" content=\"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T16:28:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/indigenous-perspectives-for-lake-winnipeg-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/\",\"name\":\"Perspectivas ind\u00edgenas respecto al lago Winnipeg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/indigenous-perspectives-for-lake-winnipeg.jpg\",\"datePublished\":\"2013-12-02T23:24:57+00:00\",\"dateModified\":\"2024-06-22T16:28:13+00:00\",\"description\":\"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/indigenous-perspectives-for-lake-winnipeg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/indigenous-perspectives-for-lake-winnipeg.jpg\",\"width\":4272,\"height\":2848,\"caption\":\"Indigenous Perspectives for Lake Winnipeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/north-american-partnership-for-environmental-community-action\\\/napeca-grants\\\/perspectivas-indigenas-respecto-al-lago-winnipeg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectivas ind\u00edgenas respecto al lago Winnipeg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Three countries working together to protect our shared environment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perspectivas ind\u00edgenas respecto al lago Winnipeg","description":"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/","og_locale":"es_ES","og_type":"article","og_title":"Perspectivas ind\u00edgenas respecto al lago Winnipeg","og_description":"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades","og_url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-06-22T16:28:13+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/indigenous-perspectives-for-lake-winnipeg-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/","url":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/","name":"Perspectivas ind\u00edgenas respecto al lago Winnipeg","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/indigenous-perspectives-for-lake-winnipeg.jpg","datePublished":"2013-12-02T23:24:57+00:00","dateModified":"2024-06-22T16:28:13+00:00","description":"ANTECEDENTES El lago Winnipeg es el d\u00e9cimo m\u00e1s grande del mundo; su cuenca abarca dos pa\u00edses, cuatro provincias, cuatro estados y m\u00e1s de cien comunidades","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/indigenous-perspectives-for-lake-winnipeg.jpg","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/2019\/09\/indigenous-perspectives-for-lake-winnipeg.jpg","width":4272,"height":2848,"caption":"Indigenous Perspectives for Lake Winnipeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/north-american-partnership-for-environmental-community-action\/napeca-grants\/perspectivas-indigenas-respecto-al-lago-winnipeg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Perspectivas ind\u00edgenas respecto al lago Winnipeg"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Three countries working together to protect our shared environment","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants\/11237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/grants"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/grants"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/2948"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=11237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}