{"id":57851,"date":"2025-03-03T11:59:56","date_gmt":"2025-03-03T16:59:56","guid":{"rendered":"https:\/\/www.cec.org\/events\/mesa-redonda-pymes-y-sostenibilidad\/"},"modified":"2025-08-28T14:34:53","modified_gmt":"2025-08-28T18:34:53","slug":"mesa-redonda-pymes-y-sostenibilidad","status":"publish","type":"events","link":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/","title":{"rendered":"Mesa redonda Pymes y sostenibilidad: retos y oportunidades en Am\u00e9rica del Norte"},"content":{"rendered":"<p>Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n mexicana C\u00e1mara Nacional de la Industria de Transformaci\u00f3n (CANACINTRA), esta mesa redonda presencial de medio d\u00eda reuni\u00f3 a representantes de peque\u00f1as y medianas empresas \u2014pymes\u2014 de Canad\u00e1, Estados Unidos y M\u00e9xico, para discutir los retos y las oportunidades de integrar pr\u00e1cticas sostenibles en sus operaciones. Las personas que participaron a este evento contribuyeron a explorar c\u00f3mo las pymes pueden convertirse en motores clave de un futuro m\u00e1s verde y sostenible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n mexicana C\u00e1mara Nacional de la Industria de Transformaci\u00f3n (CANACINTRA), esta mesa redonda presencial de medio d\u00eda reuni\u00f3 a representantes de peque\u00f1as y medianas empresas \u2014pymes\u2014 de Canad\u00e1, Estados Unidos [&hellip;]<\/p>\n","protected":false},"featured_media":59274,"template":"","class_list":["post-57851","events","type-events","status-publish","has-post-thumbnail","hentry","event_category-otro-evento","country-mexico-es","participation-por-invitacion-solamente","themes-alianzas-externas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roundtable SMEs and Sustainability<\/title>\n<meta name=\"description\" content=\"Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa redonda Pymes y sostenibilidad: retos y oportunidades en Am\u00e9rica del Norte\" \/>\n<meta property=\"og:description\" content=\"CEC events range from large public consultations to small, expert meetings on specific environmental issues.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T18:34:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/CEC_PrivSec_Roundtable2_1200x684-ES.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/\",\"name\":\"Roundtable SMEs and Sustainability\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC_PrivSec_Roundtable2_1200x684-ES.webp\",\"datePublished\":\"2025-03-03T16:59:56+00:00\",\"dateModified\":\"2025-08-28T18:34:53+00:00\",\"description\":\"Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC_PrivSec_Roundtable2_1200x684-ES.webp\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC_PrivSec_Roundtable2_1200x684-ES.webp\",\"width\":2500,\"height\":1425,\"caption\":\"SMEs and Sustainability\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/mesa-redonda-pymes-y-sostenibilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mesa redonda Pymes y sostenibilidad: retos y oportunidades en Am\u00e9rica del Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roundtable SMEs and Sustainability","description":"Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa redonda Pymes y sostenibilidad: retos y oportunidades en Am\u00e9rica del Norte","og_description":"CEC events range from large public consultations to small, expert meetings on specific environmental issues.","og_url":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2025-08-28T18:34:53+00:00","og_image":[{"width":2500,"height":1425,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC_PrivSec_Roundtable2_1200x684-ES.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/","url":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/","name":"Roundtable SMEs and Sustainability","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC_PrivSec_Roundtable2_1200x684-ES.webp","datePublished":"2025-03-03T16:59:56+00:00","dateModified":"2025-08-28T18:34:53+00:00","description":"Celebrada en la Ciudad de M\u00e9xico el 3 de diciembre de 2024, como evento coorganizado por la Comisi\u00f3n para la Cooperaci\u00f3n Ambiental (CCA) y la asociaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC_PrivSec_Roundtable2_1200x684-ES.webp","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC_PrivSec_Roundtable2_1200x684-ES.webp","width":2500,"height":1425,"caption":"SMEs and Sustainability"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/eventos\/mesa-redonda-pymes-y-sostenibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.cec.org\/es\/eventos\/"},{"@type":"ListItem","position":3,"name":"Mesa redonda Pymes y sostenibilidad: retos y oportunidades en Am\u00e9rica del Norte"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/events\/57851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/59274"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=57851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}