{"id":55181,"date":"2024-04-29T13:09:28","date_gmt":"2024-04-29T17:09:28","guid":{"rendered":"http:\/\/www.cec.org\/ej4climate\/ej4climate-grants\/escuelas-refrescantes-en-el-condado-de-franklin\/"},"modified":"2024-07-11T14:09:08","modified_gmt":"2024-07-11T18:09:08","slug":"escuelas-refrescantes-en-el-condado-de-franklin","status":"publish","type":"ej4climate","link":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/","title":{"rendered":"Escuelas frescas en el condado de Franklin"},"content":{"rendered":"<p><strong>Antecedentes<\/strong><\/p>\n<p>La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado en toda el\u00a0\u00e1rea metropolitana, los puntos cr\u00edticos del centro de la ciudad y las comunidades con pocos \u00e1rboles est\u00e1n ardiendo. Como consecuencia de la exclusi\u00f3n social, nuestras comunidades de bajos ingresos carecen de un acceso equitativo a un arbolado robusto. En un esfuerzo por apoyar el Plan Maestro de Silvicultura Urbana de Columbus (<em>Columbus Urban Forestry Master Plan<\/em>), Green Columbus est\u00e1 dando un\u00a0paso adelante para plantar \u00e1rboles en extensos terrenos de propiedad privada: m\u00e1s espec\u00edficamente, en\u00a0escuelas. Al sembrar un denso dosel de \u00e1rboles nativos alrededor de patios de recreo y cerca de estacionamientos, y dar sombra a las paradas de\u00a0autob\u00fas, entre otras medidas, podemos ayudar a mantener frescos y utilizables los patios de los centros escolares para las generaciones futuras. Estos \u00e1rboles contribuir\u00e1n, adem\u00e1s, a reducir las tasas de asma y los montos de las facturas de servicios p\u00fablicos.<strong>\u00a0<\/strong><\/p>\n<p><strong>Metas<\/strong><\/p>\n<p>Nuestro principal objetivo es crear una cultura que se interese por los \u00e1rboles y la equidad ambiental en la regi\u00f3n central de Ohio, al tiempo que aumentamos nuestro dosel arb\u00f3reo plantando m\u00e1s de 200 \u00e1rboles de gran copa en terrenos de los centros escolares de la ciudad de Columbus.<\/p>\n<p><strong>Actividades principales<\/strong><\/p>\n<p>Con el fin de involucrar a los alumnos y explicarles la complejidad de la equidad arb\u00f3rea, crearemos un cuestionario previo y otro posterior al proyecto; realizaremos visitas programadas a las aulas de los centros escolares; colaboraremos con docentes de la localidad a fin de identificar vac\u00edos o deficiencias; nos reuniremos con organizaciones educativas para conocer y obtener los materiales de que actualmente se dispone, y organizaremos actividades interactivas.<\/p>\n<p>Cuando llegue el momento de plantar, seleccionaremos las especies seg\u00fan las predicciones clim\u00e1ticas del Departamento de Agricultura de Estados Unidos (<em>United States Department of Agriculture<\/em>, USDA); contrataremos a un equipo local dedicado a la plantaci\u00f3n; compraremos suministros de apoyo, y colaboraremos con las escuelas de la ciudad de Columbus para completar la plantaci\u00f3n.<\/p>\n<p>Una vez plantados los \u00e1rboles, compraremos suministros para el mantenimiento; redactaremos un contrato de mantenimiento con un arboricultor; estableceremos un calendario de seguimiento (monitoreo) basado en las fechas de plantaci\u00f3n, y nos aseguraremos de que los \u00e1rboles sobreviven el trasplante.<strong>\u00a0<\/strong><\/p>\n<p><strong>Resultados previstos<\/strong><\/p>\n<p>Uno de los principales resultados de este proyecto ser\u00e1 que los alumnos reconozcan los numerosos beneficios que los \u00e1rboles nativos tienen para su comunidad y para la mitigaci\u00f3n del calor extremo en general. Tambi\u00e9n tendr\u00e1n la oportunidad de participar en actividades escolares reproducibles que contribuir\u00e1n al involucramiento de alumnos de todo Ohio en tareas de silvicultura urbana.<\/p>\n<p>Con 245 \u00e1rboles plantados, esperamos tener una decena de planteles escolares totalmente arbolados al t\u00e9rmino del proyecto. Mediante un plan de monitoreo y mantenimiento supervisado por un arboricultor de la comunidad, pretendemos asegurarnos de que los \u00e1rboles sobreviven al trasplante para echar nuevas ra\u00edces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado en toda el\u00a0\u00e1rea metropolitana, los puntos cr\u00edticos del centro de la ciudad y las comunidades con pocos \u00e1rboles est\u00e1n ardiendo. Como consecuencia de la exclusi\u00f3n social, nuestras comunidades de [&hellip;]<\/p>\n","protected":false},"featured_media":55152,"template":"","class_list":["post-55181","ej4climate","type-ej4climate","status-publish","has-post-thumbnail","hentry","country-estados-unidos","status-activo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escuelas frescas en el condado de Franklin<\/title>\n<meta name=\"description\" content=\"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuelas frescas en el condado de Franklin\" \/>\n<meta property=\"og:description\" content=\"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/\" \/>\n<meta property=\"og:site_name\" content=\"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CECconnect\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T18:09:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cec.org\/wp-content\/uploads\/Green-Columbus.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CECweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/\",\"name\":\"Escuelas frescas en el condado de Franklin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/Green-Columbus.webp\",\"datePublished\":\"2024-04-29T17:09:28+00:00\",\"dateModified\":\"2024-07-11T18:09:08+00:00\",\"description\":\"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/Green-Columbus.webp\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/Green-Columbus.webp\",\"width\":1200,\"height\":684,\"caption\":\"@ Green Columbus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/ej4climate\\\/subvenciones-ej4climate\\\/escuelas-refrescantes-en-el-condado-de-franklin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuelas frescas en el condado de Franklin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"name\":\"Commission for Environmental Cooperation\",\"description\":\"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\"},\"alternateName\":\"CEC - CCA - CCE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cec.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#organization\",\"name\":\"Commission for Environmental Cooperation\",\"alternateName\":\"CEC - CCA - CCE\",\"url\":\"https:\\\/\\\/www.cec.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.cec.org\\\/wp-content\\\/uploads\\\/CEC-Logo-RGB.png\",\"width\":490,\"height\":490,\"caption\":\"Commission for Environmental Cooperation\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cec.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CECconnect\",\"https:\\\/\\\/x.com\\\/CECweb\",\"https:\\\/\\\/www.instagram.com\\\/cecnorthamerica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/commission-for-environmental-cooperation-of-north-america\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CECweb\"],\"description\":\"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.\",\"email\":\"info@cec.org\",\"telephone\":\"+1 (514) 350-4300\",\"legalName\":\"Commission for Environmental Cooperation\",\"foundingDate\":\"1994-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityStaffingReport\":\"https:\\\/\\\/www.cec.org\\\/about\\\/secretariat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escuelas frescas en el condado de Franklin","description":"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/","og_locale":"es_ES","og_type":"article","og_title":"Escuelas frescas en el condado de Franklin","og_description":"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado","og_url":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/","og_site_name":"Comisi\u00f3n para la Cooperaci\u00f3n Ambiental","article_publisher":"https:\/\/www.facebook.com\/CECconnect","article_modified_time":"2024-07-11T18:09:08+00:00","og_image":[{"width":1200,"height":684,"url":"https:\/\/www.cec.org\/wp-content\/uploads\/Green-Columbus.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@CECweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/","url":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/","name":"Escuelas frescas en el condado de Franklin","isPartOf":{"@id":"https:\/\/www.cec.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/#primaryimage"},"image":{"@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/Green-Columbus.webp","datePublished":"2024-04-29T17:09:28+00:00","dateModified":"2024-07-11T18:09:08+00:00","description":"Antecedentes La ciudad de Columbus, Ohio, alberga la isla de calor urbana de m\u00e1s r\u00e1pido crecimiento de Estados Unidos. Con s\u00f3lo 22 por ciento de arbolado","breadcrumb":{"@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/#primaryimage","url":"https:\/\/www.cec.org\/wp-content\/uploads\/Green-Columbus.webp","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/Green-Columbus.webp","width":1200,"height":684,"caption":"@ Green Columbus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cec.org\/es\/ej4climate\/subvenciones-ej4climate\/escuelas-refrescantes-en-el-condado-de-franklin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cec.org\/es\/"},{"@type":"ListItem","position":2,"name":"Escuelas frescas en el condado de Franklin"}]},{"@type":"WebSite","@id":"https:\/\/www.cec.org\/es\/#website","url":"https:\/\/www.cec.org\/es\/","name":"Commission for Environmental Cooperation","description":"Tres pa\u00edses unidos en la protecci\u00f3n del medio ambiente que compartimos","publisher":{"@id":"https:\/\/www.cec.org\/es\/#organization"},"alternateName":"CEC - CCA - CCE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cec.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cec.org\/es\/#organization","name":"Commission for Environmental Cooperation","alternateName":"CEC - CCA - CCE","url":"https:\/\/www.cec.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","contentUrl":"https:\/\/www.cec.org\/wp-content\/uploads\/CEC-Logo-RGB.png","width":490,"height":490,"caption":"Commission for Environmental Cooperation"},"image":{"@id":"https:\/\/www.cec.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CECconnect","https:\/\/x.com\/CECweb","https:\/\/www.instagram.com\/cecnorthamerica\/","https:\/\/www.linkedin.com\/company\/commission-for-environmental-cooperation-of-north-america\/?viewAsMember=true","https:\/\/www.youtube.com\/user\/CECweb"],"description":"The Commission for Environmental Cooperation (CEC) is an intergovernmental organization established to support environmental cooperation across North America. Through research, data, publications, public engagement, and collaborative initiatives, the CEC addresses shared environmental challenges, promotes sustainable development, and helps conserve the continent's ecosystems and biodiversity.","email":"info@cec.org","telephone":"+1 (514) 350-4300","legalName":"Commission for Environmental Cooperation","foundingDate":"1994-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityStaffingReport":"https:\/\/www.cec.org\/about\/secretariat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/ej4climate\/55181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/ej4climate"}],"about":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/types\/ej4climate"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media\/55152"}],"wp:attachment":[{"href":"https:\/\/www.cec.org\/es\/wp-json\/wp\/v2\/media?parent=55181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}